{"id":9714,"date":"2024-08-15T19:26:53","date_gmt":"2024-08-16T00:26:53","guid":{"rendered":"https:\/\/casaopcion.com\/es\/?post_type=property&#038;p=9714"},"modified":"2024-08-21T08:18:18","modified_gmt":"2024-08-21T13:18:18","slug":"u-402-timone-versalles-puerto-vallarta","status":"publish","type":"property","link":"https:\/\/casaopcion.com\/es\/propiedad\/u-402-timone-versalles-puerto-vallarta\/","title":{"rendered":"U-402 Timone"},"content":{"rendered":"<div>Conoce unidad<strong> 402 prototipo \u00abD\u00bb<\/strong> en el desarrollo Timone ubicado en Versalles\u00a0 Puerto Vallarta<\/div>\n<div class=\"text\">Este hermoso desarrollo es para quienes desean vivir en un entorno rodeado de monta\u00f1as y mar, con todos los servicios que ofrece una ciudad como Puerto Vallarta, Jalisco.<\/div>\n<div><\/div>\n<div>Esta unidad cuenta con una recamara y un ba\u00f1o con vestidor, adem\u00e1s de \u00e1rea de sala\/comedor, cocineta y terraza.<\/div>\n<div><\/div>\n<div>Cuenta con una\u00a0 gran ubicaci\u00f3n, con 34 departamentos, 7 niveles con elevador, estacionamiento, bodegas, 4 locales comerciales, seguridad las 24 horas del d\u00eda, Roof Garden, Ludoteca, Gimnasio, Sky bar y una impresionante vista a la bah\u00eda.<\/div>\n<div><\/div>\n<div><strong>Caracter\u00edsticas<\/strong><\/div>\n<ul>\n<li>1 recamara<\/li>\n<li>1 ba\u00f1o con vestidor<\/li>\n<li>52.87 M2 de construcci\u00f3n <strong>(569.09 sqft)<\/strong><\/li>\n<li>Sala\/Comedor<\/li>\n<li>Cocineta<\/li>\n<li>Terraza<\/li>\n<\/ul>\n<div><strong>Amenidades\u00a0<\/strong><\/div>\n<ul>\n<li>Roof Garden<\/li>\n<li>Sky Bar<\/li>\n<li>Piscina<\/li>\n<li>Fogatero<\/li>\n<li>Ludoteca<\/li>\n<li>Gym<\/li>\n<li>Seguridad 24\/7<\/li>\n<li>Elevador<\/li>\n<\/ul>\n<div><em>Esta unidad <strong>no<\/strong> cuenta con caj\u00f3n de estacionamiento ni bodega techada.<\/em><\/div>\n<div>\n<div class=\"text\"><\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Conoce unidad 402 prototipo \u00abD\u00bb en el desarrollo Timone ubicado en Versalles\u00a0 Puerto Vallarta Este hermoso desarrollo es para quienes desean vivir en un entorno rodeado de monta\u00f1as y mar, con todos los servicios que ofrece una ciudad como Puerto Vallarta, Jalisco. Esta unidad cuenta con una recamara y un ba\u00f1o con vestidor, adem\u00e1s de&#8230;<\/p>\n","protected":false},"author":3,"featured_media":9829,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","caracter\u00edsticas-propiedad":[172,59,158,60,159,45,178],"tipos-propiedad":[68,70,71,72],"ciudades-propiedad":[],"estatus-propiedad":[84],"class_list":["post-9714","property","type-property","status-publish","has-post-thumbnail","hentry","property-feature-aire-acondicionado","property-feature-alberca","property-feature-roof-garden","property-feature-seguridad-privada","property-feature-sky-bar","property-feature-swimming-pool","property-feature-terraza","property-type-condominios","property-type-cotos-privados","property-type-departamentos","property-type-desarrollos","property-status-en-venta"],"property_meta":{"REAL_HOMES_property_price":"4275715","REAL_HOMES_property_old_price":"","REAL_HOMES_property_price_prefix":"","REAL_HOMES_property_price_postfix":"","REAL_HOMES_property_size":"52.87","REAL_HOMES_property_size_postfix":"569.09","REAL_HOMES_property_lot_size":"","REAL_HOMES_property_lot_size_postfix":"","REAL_HOMES_property_bedrooms":"1","REAL_HOMES_property_bathrooms":"1","REAL_HOMES_property_garage":"","REAL_HOMES_property_id":"","REAL_HOMES_property_year_built":"","REAL_HOMES_featured":"0","REAL_HOMES_additional_details_list":[],"REAL_HOMES_property_location":{"latitude":"20.6336463","longitude":"-105.2237664","zoom":"14"},"REAL_HOMES_property_address":"Viena, Puerto Vallarta, Regi\u00f3n Costa Norte, Jalisco, 48300, M\u00e9xico","REAL_HOMES_property_map":"0","REAL_HOMES_property_images":[{"width":150,"height":150,"file":"2024\/08\/MODELO-D-2.jpg","filesize":212105,"sizes":{"medium":{"file":"MODELO-D-2-300x169.jpg","width":300,"height":169,"mime-type":"image\/jpeg","filesize":6932,"url":"https:\/\/casaopcion.com\/es\/wp-content\/uploads\/2024\/08\/MODELO-D-2-300x169.jpg"},"large":{"file":"MODELO-D-2-1024x576.jpg","width":1024,"height":576,"mime-type":"image\/jpeg","filesize":44943,"url":"https:\/\/casaopcion.com\/es\/wp-content\/uploads\/2024\/08\/MODELO-D-2-1024x576.jpg"},"thumbnail":{"file":"MODELO-D-2-150x150.jpg","width":150,"height":150,"mime-type":"image\/jpeg","filesize":5673,"url":"https:\/\/casaopcion.com\/es\/wp-content\/uploads\/2024\/08\/MODELO-D-2-150x150.jpg"},"medium_large":{"file":"MODELO-D-2-768x432.jpg","width":768,"height":432,"mime-type":"image\/jpeg","filesize":29102,"url":"https:\/\/casaopcion.com\/es\/wp-content\/uploads\/2024\/08\/MODELO-D-2-768x432.jpg"},"post-thumbnail":{"file":"MODELO-D-2-150x84.jpg","width":150,"height":84,"mime-type":"image\/jpeg","filesize":2769,"url":"https:\/\/casaopcion.com\/es\/wp-content\/uploads\/2024\/08\/MODELO-D-2-150x84.jpg"},"modern-property-child-slider":{"file":"MODELO-D-2-680x510.jpg","width":680,"height":510,"mime-type":"image\/jpeg","filesize":35642,"url":"https:\/\/casaopcion.com\/es\/wp-content\/uploads\/2024\/08\/MODELO-D-2-680x510.jpg"},"property-thumb-image":{"file":"MODELO-D-2-488x326.jpg","width":488,"height":326,"mime-type":"image\/jpeg","filesize":18319,"url":"https:\/\/casaopcion.com\/es\/wp-content\/uploads\/2024\/08\/MODELO-D-2-488x326.jpg"},"property-detail-video-image":{"file":"MODELO-D-2-818x417.jpg","width":818,"height":417,"mime-type":"image\/jpeg","filesize":31506,"url":"https:\/\/casaopcion.com\/es\/wp-content\/uploads\/2024\/08\/MODELO-D-2-818x417.jpg"},"agent-image":{"file":"MODELO-D-2-210x210.jpg","width":210,"height":210,"mime-type":"image\/jpeg","filesize":9119,"url":"https:\/\/casaopcion.com\/es\/wp-content\/uploads\/2024\/08\/MODELO-D-2-210x210.jpg"},"partners-logo":{"file":"MODELO-D-2-600x720.jpg","width":600,"height":720,"mime-type":"image\/jpeg","filesize":60860,"url":"https:\/\/casaopcion.com\/es\/wp-content\/uploads\/2024\/08\/MODELO-D-2-600x720.jpg"},"post-featured-image":{"file":"MODELO-D-2-1240x720.jpg","width":1240,"height":720,"mime-type":"image\/jpeg","filesize":69877,"url":"https:\/\/casaopcion.com\/es\/wp-content\/uploads\/2024\/08\/MODELO-D-2-1240x720.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]},"ID":"9702","name":"MODELO-D-2.jpg","path":"\/home\/casaqpta\/casaopcion.com\/es\/wp-content\/uploads\/2024\/08\/MODELO-D-2.jpg","url":"https:\/\/casaopcion.com\/es\/wp-content\/uploads\/2024\/08\/MODELO-D-2-150x150.jpg","full_url":"https:\/\/casaopcion.com\/es\/wp-content\/uploads\/2024\/08\/MODELO-D-2.jpg","title":"MODELO D","caption":"","description":"","alt":"","srcset":"https:\/\/casaopcion.com\/es\/wp-content\/uploads\/2024\/08\/MODELO-D-2-150x150.jpg 150w, https:\/\/casaopcion.com\/es\/wp-content\/uploads\/2024\/08\/MODELO-D-2-210x210.jpg 210w"},{"width":150,"height":150,"file":"2024\/08\/timone-puerto-vallarta-versalles-desarrollo-3.jpg","filesize":919961,"sizes":{"medium":{"file":"timone-puerto-vallarta-versalles-desarrollo-3-300x169.jpg","width":300,"height":169,"mime-type":"image\/jpeg","filesize":17704,"url":"https:\/\/casaopcion.com\/es\/wp-content\/uploads\/2024\/08\/timone-puerto-vallarta-versalles-desarrollo-3-300x169.jpg"},"large":{"file":"timone-puerto-vallarta-versalles-desarrollo-3-1024x576.jpg","width":1024,"height":576,"mime-type":"image\/jpeg","filesize":140996,"url":"https:\/\/casaopcion.com\/es\/wp-content\/uploads\/2024\/08\/timone-puerto-vallarta-versalles-desarrollo-3-1024x576.jpg"},"thumbnail":{"file":"timone-puerto-vallarta-versalles-desarrollo-3-150x150.jpg","width":150,"height":150,"mime-type":"image\/jpeg","filesize":9580,"url":"https:\/\/casaopcion.com\/es\/wp-content\/uploads\/2024\/08\/timone-puerto-vallarta-versalles-desarrollo-3-150x150.jpg"},"medium_large":{"file":"timone-puerto-vallarta-versalles-desarrollo-3-768x432.jpg","width":768,"height":432,"mime-type":"image\/jpeg","filesize":88389,"url":"https:\/\/casaopcion.com\/es\/wp-content\/uploads\/2024\/08\/timone-puerto-vallarta-versalles-desarrollo-3-768x432.jpg"},"post-thumbnail":{"file":"timone-puerto-vallarta-versalles-desarrollo-3-150x84.jpg","width":150,"height":84,"mime-type":"image\/jpeg","filesize":5688,"url":"https:\/\/casaopcion.com\/es\/wp-content\/uploads\/2024\/08\/timone-puerto-vallarta-versalles-desarrollo-3-150x84.jpg"},"modern-property-child-slider":{"file":"timone-puerto-vallarta-versalles-desarrollo-3-680x510.jpg","width":680,"height":510,"mime-type":"image\/jpeg","filesize":95267,"url":"https:\/\/casaopcion.com\/es\/wp-content\/uploads\/2024\/08\/timone-puerto-vallarta-versalles-desarrollo-3-680x510.jpg"},"property-thumb-image":{"file":"timone-puerto-vallarta-versalles-desarrollo-3-488x326.jpg","width":488,"height":326,"mime-type":"image\/jpeg","filesize":48548,"url":"https:\/\/casaopcion.com\/es\/wp-content\/uploads\/2024\/08\/timone-puerto-vallarta-versalles-desarrollo-3-488x326.jpg"},"property-detail-video-image":{"file":"timone-puerto-vallarta-versalles-desarrollo-3-818x417.jpg","width":818,"height":417,"mime-type":"image\/jpeg","filesize":91480,"url":"https:\/\/casaopcion.com\/es\/wp-content\/uploads\/2024\/08\/timone-puerto-vallarta-versalles-desarrollo-3-818x417.jpg"},"agent-image":{"file":"timone-puerto-vallarta-versalles-desarrollo-3-210x210.jpg","width":210,"height":210,"mime-type":"image\/jpeg","filesize":17099,"url":"https:\/\/casaopcion.com\/es\/wp-content\/uploads\/2024\/08\/timone-puerto-vallarta-versalles-desarrollo-3-210x210.jpg"},"partners-logo":{"file":"timone-puerto-vallarta-versalles-desarrollo-3-600x720.jpg","width":600,"height":720,"mime-type":"image\/jpeg","filesize":111053,"url":"https:\/\/casaopcion.com\/es\/wp-content\/uploads\/2024\/08\/timone-puerto-vallarta-versalles-desarrollo-3-600x720.jpg"},"post-featured-image":{"file":"timone-puerto-vallarta-versalles-desarrollo-3-1240x720.jpg","width":1240,"height":720,"mime-type":"image\/jpeg","filesize":217895,"url":"https:\/\/casaopcion.com\/es\/wp-content\/uploads\/2024\/08\/timone-puerto-vallarta-versalles-desarrollo-3-1240x720.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]},"ID":"9664","name":"timone-puerto-vallarta-versalles-desarrollo-3.jpg","path":"\/home\/casaqpta\/casaopcion.com\/es\/wp-content\/uploads\/2024\/08\/timone-puerto-vallarta-versalles-desarrollo-3.jpg","url":"https:\/\/casaopcion.com\/es\/wp-content\/uploads\/2024\/08\/timone-puerto-vallarta-versalles-desarrollo-3-150x150.jpg","full_url":"https:\/\/casaopcion.com\/es\/wp-content\/uploads\/2024\/08\/timone-puerto-vallarta-versalles-desarrollo-3.jpg","title":"timone-puerto-vallarta-versalles-desarrollo-3","caption":"","description":"","alt":"","srcset":"https:\/\/casaopcion.com\/es\/wp-content\/uploads\/2024\/08\/timone-puerto-vallarta-versalles-desarrollo-3-150x150.jpg 150w, https:\/\/casaopcion.com\/es\/wp-content\/uploads\/2024\/08\/timone-puerto-vallarta-versalles-desarrollo-3-210x210.jpg 210w"},{"width":150,"height":150,"file":"2024\/08\/timone-puerto-vallarta-versalles-desarrollo-2.jpg","filesize":1142742,"sizes":{"medium":{"file":"timone-puerto-vallarta-versalles-desarrollo-2-300x169.jpg","width":300,"height":169,"mime-type":"image\/jpeg","filesize":19895,"url":"https:\/\/casaopcion.com\/es\/wp-content\/uploads\/2024\/08\/timone-puerto-vallarta-versalles-desarrollo-2-300x169.jpg"},"large":{"file":"timone-puerto-vallarta-versalles-desarrollo-2-1024x576.jpg","width":1024,"height":576,"mime-type":"image\/jpeg","filesize":178283,"url":"https:\/\/casaopcion.com\/es\/wp-content\/uploads\/2024\/08\/timone-puerto-vallarta-versalles-desarrollo-2-1024x576.jpg"},"thumbnail":{"file":"timone-puerto-vallarta-versalles-desarrollo-2-150x150.jpg","width":150,"height":150,"mime-type":"image\/jpeg","filesize":9964,"url":"https:\/\/casaopcion.com\/es\/wp-content\/uploads\/2024\/08\/timone-puerto-vallarta-versalles-desarrollo-2-150x150.jpg"},"medium_large":{"file":"timone-puerto-vallarta-versalles-desarrollo-2-768x432.jpg","width":768,"height":432,"mime-type":"image\/jpeg","filesize":109615,"url":"https:\/\/casaopcion.com\/es\/wp-content\/uploads\/2024\/08\/timone-puerto-vallarta-versalles-desarrollo-2-768x432.jpg"},"post-thumbnail":{"file":"timone-puerto-vallarta-versalles-desarrollo-2-150x84.jpg","width":150,"height":84,"mime-type":"image\/jpeg","filesize":6036,"url":"https:\/\/casaopcion.com\/es\/wp-content\/uploads\/2024\/08\/timone-puerto-vallarta-versalles-desarrollo-2-150x84.jpg"},"modern-property-child-slider":{"file":"timone-puerto-vallarta-versalles-desarrollo-2-680x510.jpg","width":680,"height":510,"mime-type":"image\/jpeg","filesize":111182,"url":"https:\/\/casaopcion.com\/es\/wp-content\/uploads\/2024\/08\/timone-puerto-vallarta-versalles-desarrollo-2-680x510.jpg"},"property-thumb-image":{"file":"timone-puerto-vallarta-versalles-desarrollo-2-488x326.jpg","width":488,"height":326,"mime-type":"image\/jpeg","filesize":56876,"url":"https:\/\/casaopcion.com\/es\/wp-content\/uploads\/2024\/08\/timone-puerto-vallarta-versalles-desarrollo-2-488x326.jpg"},"property-detail-video-image":{"file":"timone-puerto-vallarta-versalles-desarrollo-2-818x417.jpg","width":818,"height":417,"mime-type":"image\/jpeg","filesize":114094,"url":"https:\/\/casaopcion.com\/es\/wp-content\/uploads\/2024\/08\/timone-puerto-vallarta-versalles-desarrollo-2-818x417.jpg"},"agent-image":{"file":"timone-puerto-vallarta-versalles-desarrollo-2-210x210.jpg","width":210,"height":210,"mime-type":"image\/jpeg","filesize":18535,"url":"https:\/\/casaopcion.com\/es\/wp-content\/uploads\/2024\/08\/timone-puerto-vallarta-versalles-desarrollo-2-210x210.jpg"},"partners-logo":{"file":"timone-puerto-vallarta-versalles-desarrollo-2-600x720.jpg","width":600,"height":720,"mime-type":"image\/jpeg","filesize":140461,"url":"https:\/\/casaopcion.com\/es\/wp-content\/uploads\/2024\/08\/timone-puerto-vallarta-versalles-desarrollo-2-600x720.jpg"},"post-featured-image":{"file":"timone-puerto-vallarta-versalles-desarrollo-2-1240x720.jpg","width":1240,"height":720,"mime-type":"image\/jpeg","filesize":282657,"url":"https:\/\/casaopcion.com\/es\/wp-content\/uploads\/2024\/08\/timone-puerto-vallarta-versalles-desarrollo-2-1240x720.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]},"ID":"9663","name":"timone-puerto-vallarta-versalles-desarrollo-2.jpg","path":"\/home\/casaqpta\/casaopcion.com\/es\/wp-content\/uploads\/2024\/08\/timone-puerto-vallarta-versalles-desarrollo-2.jpg","url":"https:\/\/casaopcion.com\/es\/wp-content\/uploads\/2024\/08\/timone-puerto-vallarta-versalles-desarrollo-2-150x150.jpg","full_url":"https:\/\/casaopcion.com\/es\/wp-content\/uploads\/2024\/08\/timone-puerto-vallarta-versalles-desarrollo-2.jpg","title":"timone-puerto-vallarta-versalles-desarrollo-2","caption":"","description":"","alt":"","srcset":"https:\/\/casaopcion.com\/es\/wp-content\/uploads\/2024\/08\/timone-puerto-vallarta-versalles-desarrollo-2-150x150.jpg 150w, https:\/\/casaopcion.com\/es\/wp-content\/uploads\/2024\/08\/timone-puerto-vallarta-versalles-desarrollo-2-210x210.jpg 210w"},{"width":150,"height":150,"file":"2024\/08\/timone-puerto-vallarta-versalles-desarrollo-1.jpg","filesize":1219412,"sizes":{"medium":{"file":"timone-puerto-vallarta-versalles-desarrollo-1-300x169.jpg","width":300,"height":169,"mime-type":"image\/jpeg","filesize":19707,"url":"https:\/\/casaopcion.com\/es\/wp-content\/uploads\/2024\/08\/timone-puerto-vallarta-versalles-desarrollo-1-300x169.jpg"},"large":{"file":"timone-puerto-vallarta-versalles-desarrollo-1-1024x576.jpg","width":1024,"height":576,"mime-type":"image\/jpeg","filesize":170969,"url":"https:\/\/casaopcion.com\/es\/wp-content\/uploads\/2024\/08\/timone-puerto-vallarta-versalles-desarrollo-1-1024x576.jpg"},"thumbnail":{"file":"timone-puerto-vallarta-versalles-desarrollo-1-150x150.jpg","width":150,"height":150,"mime-type":"image\/jpeg","filesize":10290,"url":"https:\/\/casaopcion.com\/es\/wp-content\/uploads\/2024\/08\/timone-puerto-vallarta-versalles-desarrollo-1-150x150.jpg"},"medium_large":{"file":"timone-puerto-vallarta-versalles-desarrollo-1-768x432.jpg","width":768,"height":432,"mime-type":"image\/jpeg","filesize":105665,"url":"https:\/\/casaopcion.com\/es\/wp-content\/uploads\/2024\/08\/timone-puerto-vallarta-versalles-desarrollo-1-768x432.jpg"},"post-thumbnail":{"file":"timone-puerto-vallarta-versalles-desarrollo-1-150x84.jpg","width":150,"height":84,"mime-type":"image\/jpeg","filesize":6019,"url":"https:\/\/casaopcion.com\/es\/wp-content\/uploads\/2024\/08\/timone-puerto-vallarta-versalles-desarrollo-1-150x84.jpg"},"modern-property-child-slider":{"file":"timone-puerto-vallarta-versalles-desarrollo-1-680x510.jpg","width":680,"height":510,"mime-type":"image\/jpeg","filesize":110457,"url":"https:\/\/casaopcion.com\/es\/wp-content\/uploads\/2024\/08\/timone-puerto-vallarta-versalles-desarrollo-1-680x510.jpg"},"property-thumb-image":{"file":"timone-puerto-vallarta-versalles-desarrollo-1-488x326.jpg","width":488,"height":326,"mime-type":"image\/jpeg","filesize":56010,"url":"https:\/\/casaopcion.com\/es\/wp-content\/uploads\/2024\/08\/timone-puerto-vallarta-versalles-desarrollo-1-488x326.jpg"},"property-detail-video-image":{"file":"timone-puerto-vallarta-versalles-desarrollo-1-818x417.jpg","width":818,"height":417,"mime-type":"image\/jpeg","filesize":106601,"url":"https:\/\/casaopcion.com\/es\/wp-content\/uploads\/2024\/08\/timone-puerto-vallarta-versalles-desarrollo-1-818x417.jpg"},"agent-image":{"file":"timone-puerto-vallarta-versalles-desarrollo-1-210x210.jpg","width":210,"height":210,"mime-type":"image\/jpeg","filesize":18660,"url":"https:\/\/casaopcion.com\/es\/wp-content\/uploads\/2024\/08\/timone-puerto-vallarta-versalles-desarrollo-1-210x210.jpg"},"partners-logo":{"file":"timone-puerto-vallarta-versalles-desarrollo-1-600x720.jpg","width":600,"height":720,"mime-type":"image\/jpeg","filesize":143392,"url":"https:\/\/casaopcion.com\/es\/wp-content\/uploads\/2024\/08\/timone-puerto-vallarta-versalles-desarrollo-1-600x720.jpg"},"post-featured-image":{"file":"timone-puerto-vallarta-versalles-desarrollo-1-1240x720.jpg","width":1240,"height":720,"mime-type":"image\/jpeg","filesize":275208,"url":"https:\/\/casaopcion.com\/es\/wp-content\/uploads\/2024\/08\/timone-puerto-vallarta-versalles-desarrollo-1-1240x720.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]},"ID":"9662","name":"timone-puerto-vallarta-versalles-desarrollo-1.jpg","path":"\/home\/casaqpta\/casaopcion.com\/es\/wp-content\/uploads\/2024\/08\/timone-puerto-vallarta-versalles-desarrollo-1.jpg","url":"https:\/\/casaopcion.com\/es\/wp-content\/uploads\/2024\/08\/timone-puerto-vallarta-versalles-desarrollo-1-150x150.jpg","full_url":"https:\/\/casaopcion.com\/es\/wp-content\/uploads\/2024\/08\/timone-puerto-vallarta-versalles-desarrollo-1.jpg","title":"timone-puerto-vallarta-versalles-desarrollo-1","caption":"","description":"","alt":"","srcset":"https:\/\/casaopcion.com\/es\/wp-content\/uploads\/2024\/08\/timone-puerto-vallarta-versalles-desarrollo-1-150x150.jpg 150w, https:\/\/casaopcion.com\/es\/wp-content\/uploads\/2024\/08\/timone-puerto-vallarta-versalles-desarrollo-1-210x210.jpg 210w"},{"width":150,"height":150,"file":"2024\/08\/timone-puerto-vallarta-versalles-desarrollo-8.jpg","filesize":653188,"sizes":{"medium":{"file":"timone-puerto-vallarta-versalles-desarrollo-8-300x169.jpg","width":300,"height":169,"mime-type":"image\/jpeg","filesize":13281,"url":"https:\/\/casaopcion.com\/es\/wp-content\/uploads\/2024\/08\/timone-puerto-vallarta-versalles-desarrollo-8-300x169.jpg"},"large":{"file":"timone-puerto-vallarta-versalles-desarrollo-8-1024x576.jpg","width":1024,"height":576,"mime-type":"image\/jpeg","filesize":97111,"url":"https:\/\/casaopcion.com\/es\/wp-content\/uploads\/2024\/08\/timone-puerto-vallarta-versalles-desarrollo-8-1024x576.jpg"},"thumbnail":{"file":"timone-puerto-vallarta-versalles-desarrollo-8-150x150.jpg","width":150,"height":150,"mime-type":"image\/jpeg","filesize":6319,"url":"https:\/\/casaopcion.com\/es\/wp-content\/uploads\/2024\/08\/timone-puerto-vallarta-versalles-desarrollo-8-150x150.jpg"},"medium_large":{"file":"timone-puerto-vallarta-versalles-desarrollo-8-768x432.jpg","width":768,"height":432,"mime-type":"image\/jpeg","filesize":60808,"url":"https:\/\/casaopcion.com\/es\/wp-content\/uploads\/2024\/08\/timone-puerto-vallarta-versalles-desarrollo-8-768x432.jpg"},"post-thumbnail":{"file":"timone-puerto-vallarta-versalles-desarrollo-8-150x84.jpg","width":150,"height":84,"mime-type":"image\/jpeg","filesize":4664,"url":"https:\/\/casaopcion.com\/es\/wp-content\/uploads\/2024\/08\/timone-puerto-vallarta-versalles-desarrollo-8-150x84.jpg"},"modern-property-child-slider":{"file":"timone-puerto-vallarta-versalles-desarrollo-8-680x510.jpg","width":680,"height":510,"mime-type":"image\/jpeg","filesize":59694,"url":"https:\/\/casaopcion.com\/es\/wp-content\/uploads\/2024\/08\/timone-puerto-vallarta-versalles-desarrollo-8-680x510.jpg"},"property-thumb-image":{"file":"timone-puerto-vallarta-versalles-desarrollo-8-488x326.jpg","width":488,"height":326,"mime-type":"image\/jpeg","filesize":31171,"url":"https:\/\/casaopcion.com\/es\/wp-content\/uploads\/2024\/08\/timone-puerto-vallarta-versalles-desarrollo-8-488x326.jpg"},"property-detail-video-image":{"file":"timone-puerto-vallarta-versalles-desarrollo-8-818x417.jpg","width":818,"height":417,"mime-type":"image\/jpeg","filesize":62957,"url":"https:\/\/casaopcion.com\/es\/wp-content\/uploads\/2024\/08\/timone-puerto-vallarta-versalles-desarrollo-8-818x417.jpg"},"agent-image":{"file":"timone-puerto-vallarta-versalles-desarrollo-8-210x210.jpg","width":210,"height":210,"mime-type":"image\/jpeg","filesize":10818,"url":"https:\/\/casaopcion.com\/es\/wp-content\/uploads\/2024\/08\/timone-puerto-vallarta-versalles-desarrollo-8-210x210.jpg"},"partners-logo":{"file":"timone-puerto-vallarta-versalles-desarrollo-8-600x720.jpg","width":600,"height":720,"mime-type":"image\/jpeg","filesize":79178,"url":"https:\/\/casaopcion.com\/es\/wp-content\/uploads\/2024\/08\/timone-puerto-vallarta-versalles-desarrollo-8-600x720.jpg"},"post-featured-image":{"file":"timone-puerto-vallarta-versalles-desarrollo-8-1240x720.jpg","width":1240,"height":720,"mime-type":"image\/jpeg","filesize":151941,"url":"https:\/\/casaopcion.com\/es\/wp-content\/uploads\/2024\/08\/timone-puerto-vallarta-versalles-desarrollo-8-1240x720.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]},"ID":"9660","name":"timone-puerto-vallarta-versalles-desarrollo-8.jpg","path":"\/home\/casaqpta\/casaopcion.com\/es\/wp-content\/uploads\/2024\/08\/timone-puerto-vallarta-versalles-desarrollo-8.jpg","url":"https:\/\/casaopcion.com\/es\/wp-content\/uploads\/2024\/08\/timone-puerto-vallarta-versalles-desarrollo-8-150x150.jpg","full_url":"https:\/\/casaopcion.com\/es\/wp-content\/uploads\/2024\/08\/timone-puerto-vallarta-versalles-desarrollo-8.jpg","title":"timone-puerto-vallarta-versalles-desarrollo-8","caption":"","description":"","alt":"","srcset":"https:\/\/casaopcion.com\/es\/wp-content\/uploads\/2024\/08\/timone-puerto-vallarta-versalles-desarrollo-8-150x150.jpg 150w, https:\/\/casaopcion.com\/es\/wp-content\/uploads\/2024\/08\/timone-puerto-vallarta-versalles-desarrollo-8-210x210.jpg 210w"},{"width":150,"height":150,"file":"2024\/08\/timone-puerto-vallarta-versalles-desarrollo-7.jpg","filesize":668410,"sizes":{"medium":{"file":"timone-puerto-vallarta-versalles-desarrollo-7-300x169.jpg","width":300,"height":169,"mime-type":"image\/jpeg","filesize":12947,"url":"https:\/\/casaopcion.com\/es\/wp-content\/uploads\/2024\/08\/timone-puerto-vallarta-versalles-desarrollo-7-300x169.jpg"},"large":{"file":"timone-puerto-vallarta-versalles-desarrollo-7-1024x576.jpg","width":1024,"height":576,"mime-type":"image\/jpeg","filesize":94764,"url":"https:\/\/casaopcion.com\/es\/wp-content\/uploads\/2024\/08\/timone-puerto-vallarta-versalles-desarrollo-7-1024x576.jpg"},"thumbnail":{"file":"timone-puerto-vallarta-versalles-desarrollo-7-150x150.jpg","width":150,"height":150,"mime-type":"image\/jpeg","filesize":6211,"url":"https:\/\/casaopcion.com\/es\/wp-content\/uploads\/2024\/08\/timone-puerto-vallarta-versalles-desarrollo-7-150x150.jpg"},"medium_large":{"file":"timone-puerto-vallarta-versalles-desarrollo-7-768x432.jpg","width":768,"height":432,"mime-type":"image\/jpeg","filesize":59069,"url":"https:\/\/casaopcion.com\/es\/wp-content\/uploads\/2024\/08\/timone-puerto-vallarta-versalles-desarrollo-7-768x432.jpg"},"post-thumbnail":{"file":"timone-puerto-vallarta-versalles-desarrollo-7-150x84.jpg","width":150,"height":84,"mime-type":"image\/jpeg","filesize":4689,"url":"https:\/\/casaopcion.com\/es\/wp-content\/uploads\/2024\/08\/timone-puerto-vallarta-versalles-desarrollo-7-150x84.jpg"},"modern-property-child-slider":{"file":"timone-puerto-vallarta-versalles-desarrollo-7-680x510.jpg","width":680,"height":510,"mime-type":"image\/jpeg","filesize":58938,"url":"https:\/\/casaopcion.com\/es\/wp-content\/uploads\/2024\/08\/timone-puerto-vallarta-versalles-desarrollo-7-680x510.jpg"},"property-thumb-image":{"file":"timone-puerto-vallarta-versalles-desarrollo-7-488x326.jpg","width":488,"height":326,"mime-type":"image\/jpeg","filesize":32002,"url":"https:\/\/casaopcion.com\/es\/wp-content\/uploads\/2024\/08\/timone-puerto-vallarta-versalles-desarrollo-7-488x326.jpg"},"property-detail-video-image":{"file":"timone-puerto-vallarta-versalles-desarrollo-7-818x417.jpg","width":818,"height":417,"mime-type":"image\/jpeg","filesize":61586,"url":"https:\/\/casaopcion.com\/es\/wp-content\/uploads\/2024\/08\/timone-puerto-vallarta-versalles-desarrollo-7-818x417.jpg"},"agent-image":{"file":"timone-puerto-vallarta-versalles-desarrollo-7-210x210.jpg","width":210,"height":210,"mime-type":"image\/jpeg","filesize":10308,"url":"https:\/\/casaopcion.com\/es\/wp-content\/uploads\/2024\/08\/timone-puerto-vallarta-versalles-desarrollo-7-210x210.jpg"},"partners-logo":{"file":"timone-puerto-vallarta-versalles-desarrollo-7-600x720.jpg","width":600,"height":720,"mime-type":"image\/jpeg","filesize":70832,"url":"https:\/\/casaopcion.com\/es\/wp-content\/uploads\/2024\/08\/timone-puerto-vallarta-versalles-desarrollo-7-600x720.jpg"},"post-featured-image":{"file":"timone-puerto-vallarta-versalles-desarrollo-7-1240x720.jpg","width":1240,"height":720,"mime-type":"image\/jpeg","filesize":145992,"url":"https:\/\/casaopcion.com\/es\/wp-content\/uploads\/2024\/08\/timone-puerto-vallarta-versalles-desarrollo-7-1240x720.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]},"ID":"9659","name":"timone-puerto-vallarta-versalles-desarrollo-7.jpg","path":"\/home\/casaqpta\/casaopcion.com\/es\/wp-content\/uploads\/2024\/08\/timone-puerto-vallarta-versalles-desarrollo-7.jpg","url":"https:\/\/casaopcion.com\/es\/wp-content\/uploads\/2024\/08\/timone-puerto-vallarta-versalles-desarrollo-7-150x150.jpg","full_url":"https:\/\/casaopcion.com\/es\/wp-content\/uploads\/2024\/08\/timone-puerto-vallarta-versalles-desarrollo-7.jpg","title":"timone-puerto-vallarta-versalles-desarrollo-7","caption":"","description":"","alt":"","srcset":"https:\/\/casaopcion.com\/es\/wp-content\/uploads\/2024\/08\/timone-puerto-vallarta-versalles-desarrollo-7-150x150.jpg 150w, https:\/\/casaopcion.com\/es\/wp-content\/uploads\/2024\/08\/timone-puerto-vallarta-versalles-desarrollo-7-210x210.jpg 210w"},{"width":150,"height":150,"file":"2024\/08\/timone-puerto-vallarta-versalles-desarrollo-6.jpg","filesize":753396,"sizes":{"medium":{"file":"timone-puerto-vallarta-versalles-desarrollo-6-300x169.jpg","width":300,"height":169,"mime-type":"image\/jpeg","filesize":12883,"url":"https:\/\/casaopcion.com\/es\/wp-content\/uploads\/2024\/08\/timone-puerto-vallarta-versalles-desarrollo-6-300x169.jpg"},"large":{"file":"timone-puerto-vallarta-versalles-desarrollo-6-1024x576.jpg","width":1024,"height":576,"mime-type":"image\/jpeg","filesize":100658,"url":"https:\/\/casaopcion.com\/es\/wp-content\/uploads\/2024\/08\/timone-puerto-vallarta-versalles-desarrollo-6-1024x576.jpg"},"thumbnail":{"file":"timone-puerto-vallarta-versalles-desarrollo-6-150x150.jpg","width":150,"height":150,"mime-type":"image\/jpeg","filesize":6102,"url":"https:\/\/casaopcion.com\/es\/wp-content\/uploads\/2024\/08\/timone-puerto-vallarta-versalles-desarrollo-6-150x150.jpg"},"medium_large":{"file":"timone-puerto-vallarta-versalles-desarrollo-6-768x432.jpg","width":768,"height":432,"mime-type":"image\/jpeg","filesize":63227,"url":"https:\/\/casaopcion.com\/es\/wp-content\/uploads\/2024\/08\/timone-puerto-vallarta-versalles-desarrollo-6-768x432.jpg"},"post-thumbnail":{"file":"timone-puerto-vallarta-versalles-desarrollo-6-150x84.jpg","width":150,"height":84,"mime-type":"image\/jpeg","filesize":4606,"url":"https:\/\/casaopcion.com\/es\/wp-content\/uploads\/2024\/08\/timone-puerto-vallarta-versalles-desarrollo-6-150x84.jpg"},"modern-property-child-slider":{"file":"timone-puerto-vallarta-versalles-desarrollo-6-680x510.jpg","width":680,"height":510,"mime-type":"image\/jpeg","filesize":62445,"url":"https:\/\/casaopcion.com\/es\/wp-content\/uploads\/2024\/08\/timone-puerto-vallarta-versalles-desarrollo-6-680x510.jpg"},"property-thumb-image":{"file":"timone-puerto-vallarta-versalles-desarrollo-6-488x326.jpg","width":488,"height":326,"mime-type":"image\/jpeg","filesize":32992,"url":"https:\/\/casaopcion.com\/es\/wp-content\/uploads\/2024\/08\/timone-puerto-vallarta-versalles-desarrollo-6-488x326.jpg"},"property-detail-video-image":{"file":"timone-puerto-vallarta-versalles-desarrollo-6-818x417.jpg","width":818,"height":417,"mime-type":"image\/jpeg","filesize":65710,"url":"https:\/\/casaopcion.com\/es\/wp-content\/uploads\/2024\/08\/timone-puerto-vallarta-versalles-desarrollo-6-818x417.jpg"},"agent-image":{"file":"timone-puerto-vallarta-versalles-desarrollo-6-210x210.jpg","width":210,"height":210,"mime-type":"image\/jpeg","filesize":10338,"url":"https:\/\/casaopcion.com\/es\/wp-content\/uploads\/2024\/08\/timone-puerto-vallarta-versalles-desarrollo-6-210x210.jpg"},"partners-logo":{"file":"timone-puerto-vallarta-versalles-desarrollo-6-600x720.jpg","width":600,"height":720,"mime-type":"image\/jpeg","filesize":70028,"url":"https:\/\/casaopcion.com\/es\/wp-content\/uploads\/2024\/08\/timone-puerto-vallarta-versalles-desarrollo-6-600x720.jpg"},"post-featured-image":{"file":"timone-puerto-vallarta-versalles-desarrollo-6-1240x720.jpg","width":1240,"height":720,"mime-type":"image\/jpeg","filesize":156631,"url":"https:\/\/casaopcion.com\/es\/wp-content\/uploads\/2024\/08\/timone-puerto-vallarta-versalles-desarrollo-6-1240x720.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]},"ID":"9658","name":"timone-puerto-vallarta-versalles-desarrollo-6.jpg","path":"\/home\/casaqpta\/casaopcion.com\/es\/wp-content\/uploads\/2024\/08\/timone-puerto-vallarta-versalles-desarrollo-6.jpg","url":"https:\/\/casaopcion.com\/es\/wp-content\/uploads\/2024\/08\/timone-puerto-vallarta-versalles-desarrollo-6-150x150.jpg","full_url":"https:\/\/casaopcion.com\/es\/wp-content\/uploads\/2024\/08\/timone-puerto-vallarta-versalles-desarrollo-6.jpg","title":"timone-puerto-vallarta-versalles-desarrollo-6","caption":"","description":"","alt":"","srcset":"https:\/\/casaopcion.com\/es\/wp-content\/uploads\/2024\/08\/timone-puerto-vallarta-versalles-desarrollo-6-150x150.jpg 150w, https:\/\/casaopcion.com\/es\/wp-content\/uploads\/2024\/08\/timone-puerto-vallarta-versalles-desarrollo-6-210x210.jpg 210w"},{"width":150,"height":150,"file":"2024\/08\/timone-puerto-vallarta-versalles-desarrollo-5.jpg","filesize":727793,"sizes":{"medium":{"file":"timone-puerto-vallarta-versalles-desarrollo-5-300x169.jpg","width":300,"height":169,"mime-type":"image\/jpeg","filesize":13003,"url":"https:\/\/casaopcion.com\/es\/wp-content\/uploads\/2024\/08\/timone-puerto-vallarta-versalles-desarrollo-5-300x169.jpg"},"large":{"file":"timone-puerto-vallarta-versalles-desarrollo-5-1024x576.jpg","width":1024,"height":576,"mime-type":"image\/jpeg","filesize":102003,"url":"https:\/\/casaopcion.com\/es\/wp-content\/uploads\/2024\/08\/timone-puerto-vallarta-versalles-desarrollo-5-1024x576.jpg"},"thumbnail":{"file":"timone-puerto-vallarta-versalles-desarrollo-5-150x150.jpg","width":150,"height":150,"mime-type":"image\/jpeg","filesize":7491,"url":"https:\/\/casaopcion.com\/es\/wp-content\/uploads\/2024\/08\/timone-puerto-vallarta-versalles-desarrollo-5-150x150.jpg"},"medium_large":{"file":"timone-puerto-vallarta-versalles-desarrollo-5-768x432.jpg","width":768,"height":432,"mime-type":"image\/jpeg","filesize":62660,"url":"https:\/\/casaopcion.com\/es\/wp-content\/uploads\/2024\/08\/timone-puerto-vallarta-versalles-desarrollo-5-768x432.jpg"},"post-thumbnail":{"file":"timone-puerto-vallarta-versalles-desarrollo-5-150x84.jpg","width":150,"height":84,"mime-type":"image\/jpeg","filesize":4517,"url":"https:\/\/casaopcion.com\/es\/wp-content\/uploads\/2024\/08\/timone-puerto-vallarta-versalles-desarrollo-5-150x84.jpg"},"modern-property-child-slider":{"file":"timone-puerto-vallarta-versalles-desarrollo-5-680x510.jpg","width":680,"height":510,"mime-type":"image\/jpeg","filesize":68202,"url":"https:\/\/casaopcion.com\/es\/wp-content\/uploads\/2024\/08\/timone-puerto-vallarta-versalles-desarrollo-5-680x510.jpg"},"property-thumb-image":{"file":"timone-puerto-vallarta-versalles-desarrollo-5-488x326.jpg","width":488,"height":326,"mime-type":"image\/jpeg","filesize":34108,"url":"https:\/\/casaopcion.com\/es\/wp-content\/uploads\/2024\/08\/timone-puerto-vallarta-versalles-desarrollo-5-488x326.jpg"},"property-detail-video-image":{"file":"timone-puerto-vallarta-versalles-desarrollo-5-818x417.jpg","width":818,"height":417,"mime-type":"image\/jpeg","filesize":64257,"url":"https:\/\/casaopcion.com\/es\/wp-content\/uploads\/2024\/08\/timone-puerto-vallarta-versalles-desarrollo-5-818x417.jpg"},"agent-image":{"file":"timone-puerto-vallarta-versalles-desarrollo-5-210x210.jpg","width":210,"height":210,"mime-type":"image\/jpeg","filesize":12960,"url":"https:\/\/casaopcion.com\/es\/wp-content\/uploads\/2024\/08\/timone-puerto-vallarta-versalles-desarrollo-5-210x210.jpg"},"partners-logo":{"file":"timone-puerto-vallarta-versalles-desarrollo-5-600x720.jpg","width":600,"height":720,"mime-type":"image\/jpeg","filesize":91680,"url":"https:\/\/casaopcion.com\/es\/wp-content\/uploads\/2024\/08\/timone-puerto-vallarta-versalles-desarrollo-5-600x720.jpg"},"post-featured-image":{"file":"timone-puerto-vallarta-versalles-desarrollo-5-1240x720.jpg","width":1240,"height":720,"mime-type":"image\/jpeg","filesize":161679,"url":"https:\/\/casaopcion.com\/es\/wp-content\/uploads\/2024\/08\/timone-puerto-vallarta-versalles-desarrollo-5-1240x720.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]},"ID":"9657","name":"timone-puerto-vallarta-versalles-desarrollo-5.jpg","path":"\/home\/casaqpta\/casaopcion.com\/es\/wp-content\/uploads\/2024\/08\/timone-puerto-vallarta-versalles-desarrollo-5.jpg","url":"https:\/\/casaopcion.com\/es\/wp-content\/uploads\/2024\/08\/timone-puerto-vallarta-versalles-desarrollo-5-150x150.jpg","full_url":"https:\/\/casaopcion.com\/es\/wp-content\/uploads\/2024\/08\/timone-puerto-vallarta-versalles-desarrollo-5.jpg","title":"timone-puerto-vallarta-versalles-desarrollo-5","caption":"","description":"","alt":"","srcset":"https:\/\/casaopcion.com\/es\/wp-content\/uploads\/2024\/08\/timone-puerto-vallarta-versalles-desarrollo-5-150x150.jpg 150w, https:\/\/casaopcion.com\/es\/wp-content\/uploads\/2024\/08\/timone-puerto-vallarta-versalles-desarrollo-5-210x210.jpg 210w"},{"width":150,"height":150,"file":"2024\/08\/U-402.jpg","filesize":228209,"sizes":{"medium":{"file":"U-402-300x169.jpg","width":300,"height":169,"mime-type":"image\/jpeg","filesize":10931,"url":"https:\/\/casaopcion.com\/es\/wp-content\/uploads\/2024\/08\/U-402-300x169.jpg"},"large":{"file":"U-402-1024x576.jpg","width":1024,"height":576,"mime-type":"image\/jpeg","filesize":75725,"url":"https:\/\/casaopcion.com\/es\/wp-content\/uploads\/2024\/08\/U-402-1024x576.jpg"},"thumbnail":{"file":"U-402-150x150.jpg","width":150,"height":150,"mime-type":"image\/jpeg","filesize":6942,"url":"https:\/\/casaopcion.com\/es\/wp-content\/uploads\/2024\/08\/U-402-150x150.jpg"},"medium_large":{"file":"U-402-768x432.jpg","width":768,"height":432,"mime-type":"image\/jpeg","filesize":50104,"url":"https:\/\/casaopcion.com\/es\/wp-content\/uploads\/2024\/08\/U-402-768x432.jpg"},"post-thumbnail":{"file":"U-402-150x84.jpg","width":150,"height":84,"mime-type":"image\/jpeg","filesize":3800,"url":"https:\/\/casaopcion.com\/es\/wp-content\/uploads\/2024\/08\/U-402-150x84.jpg"},"modern-property-child-slider":{"file":"U-402-680x510.jpg","width":680,"height":510,"mime-type":"image\/jpeg","filesize":61727,"url":"https:\/\/casaopcion.com\/es\/wp-content\/uploads\/2024\/08\/U-402-680x510.jpg"},"property-thumb-image":{"file":"U-402-488x326.jpg","width":488,"height":326,"mime-type":"image\/jpeg","filesize":30967,"url":"https:\/\/casaopcion.com\/es\/wp-content\/uploads\/2024\/08\/U-402-488x326.jpg"},"property-detail-video-image":{"file":"U-402-818x417.jpg","width":818,"height":417,"mime-type":"image\/jpeg","filesize":49366,"url":"https:\/\/casaopcion.com\/es\/wp-content\/uploads\/2024\/08\/U-402-818x417.jpg"},"agent-image":{"file":"U-402-210x210.jpg","width":210,"height":210,"mime-type":"image\/jpeg","filesize":12339,"url":"https:\/\/casaopcion.com\/es\/wp-content\/uploads\/2024\/08\/U-402-210x210.jpg"},"partners-logo":{"file":"U-402-600x720.jpg","width":600,"height":720,"mime-type":"image\/jpeg","filesize":68768,"url":"https:\/\/casaopcion.com\/es\/wp-content\/uploads\/2024\/08\/U-402-600x720.jpg"},"post-featured-image":{"file":"U-402-1240x720.jpg","width":1240,"height":720,"mime-type":"image\/jpeg","filesize":111435,"url":"https:\/\/casaopcion.com\/es\/wp-content\/uploads\/2024\/08\/U-402-1240x720.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]},"ID":"9715","name":"U-402.jpg","path":"\/home\/casaqpta\/casaopcion.com\/es\/wp-content\/uploads\/2024\/08\/U-402.jpg","url":"https:\/\/casaopcion.com\/es\/wp-content\/uploads\/2024\/08\/U-402-150x150.jpg","full_url":"https:\/\/casaopcion.com\/es\/wp-content\/uploads\/2024\/08\/U-402.jpg","title":"U-402","caption":"","description":"","alt":"","srcset":"https:\/\/casaopcion.com\/es\/wp-content\/uploads\/2024\/08\/U-402-150x150.jpg 150w, https:\/\/casaopcion.com\/es\/wp-content\/uploads\/2024\/08\/U-402-210x210.jpg 210w"}],"REAL_HOMES_change_gallery_slider_type":"0","REAL_HOMES_gallery_slider_type":"thumb-on-right","inspiry_floor_plans":[],"inspiry_video_group":[],"REAL_HOMES_360_virtual_tour":"","REAL_HOMES_tour_video_url":"","REAL_HOMES_tour_video_image":[],"REAL_HOMES_agent_display_option":"none","REAL_HOMES_agents":[],"REAL_HOMES_energy_class":"none","REAL_HOMES_energy_performance":"","REAL_HOMES_epc_current_rating":"","REAL_HOMES_epc_potential_rating":"","REAL_HOMES_sticky":"0","inspiry_property_label":"","inspiry_property_label_color":"","inspiry_property_tax":"0","inspiry_additional_fee":"0","REAL_HOMES_attachments":[],"inspiry_property_owner_name":"","inspiry_property_owner_contact":"","inspiry_property_owner_address":"","REAL_HOMES_property_private_note":"","inspiry_message_to_reviewer":"","REAL_HOMES_add_in_slider":"no","REAL_HOMES_slider_image":[],"REAL_HOMES_page_banner_image":[],"REAL_HOMES_hide_property_advance_search":"0","REAL_HOMES_custom_header_display":"default","REAL_HOMES_custom_header_position":"relative","REAL_HOMES_hide_advance_search":"0","REAL_HOMES_custom_search_form":"default","REAL_HOMES_search_form_margin_top":"","REAL_HOMES_search_form_margin_bottom":"","REAL_HOMES_custom_footer_display":"default"},"_links":{"self":[{"href":"https:\/\/casaopcion.com\/es\/wp-json\/wp\/v2\/properties\/9714","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/casaopcion.com\/es\/wp-json\/wp\/v2\/properties"}],"about":[{"href":"https:\/\/casaopcion.com\/es\/wp-json\/wp\/v2\/types\/property"}],"author":[{"embeddable":true,"href":"https:\/\/casaopcion.com\/es\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/casaopcion.com\/es\/wp-json\/wp\/v2\/comments?post=9714"}],"version-history":[{"count":1,"href":"https:\/\/casaopcion.com\/es\/wp-json\/wp\/v2\/properties\/9714\/revisions"}],"predecessor-version":[{"id":9716,"href":"https:\/\/casaopcion.com\/es\/wp-json\/wp\/v2\/properties\/9714\/revisions\/9716"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/casaopcion.com\/es\/wp-json\/wp\/v2\/media\/9829"}],"wp:attachment":[{"href":"https:\/\/casaopcion.com\/es\/wp-json\/wp\/v2\/media?parent=9714"}],"wp:term":[{"taxonomy":"property-feature","embeddable":true,"href":"https:\/\/casaopcion.com\/es\/wp-json\/wp\/v2\/caracter\u00edsticas-propiedad?post=9714"},{"taxonomy":"property-type","embeddable":true,"href":"https:\/\/casaopcion.com\/es\/wp-json\/wp\/v2\/tipos-propiedad?post=9714"},{"taxonomy":"property-city","embeddable":true,"href":"https:\/\/casaopcion.com\/es\/wp-json\/wp\/v2\/ciudades-propiedad?post=9714"},{"taxonomy":"property-status","embeddable":true,"href":"https:\/\/casaopcion.com\/es\/wp-json\/wp\/v2\/estatus-propiedad?post=9714"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}