{"id":9826,"date":"2024-11-12T11:50:42","date_gmt":"2024-11-12T17:50:42","guid":{"rendered":"https:\/\/casaopcion.com\/en\/?post_type=property&#038;p=9826"},"modified":"2024-11-12T11:50:42","modified_gmt":"2024-11-12T17:50:42","slug":"u-404-timone-versalles-puerto-vallarta","status":"publish","type":"property","link":"https:\/\/casaopcion.com\/en\/property\/u-404-timone-versalles-puerto-vallarta\/","title":{"rendered":"U-404 Timone"},"content":{"rendered":"<p>Explore<strong> Unit 404, Prototype &#8220;A&#8221; <\/strong>at the Timone Development, located in Versalles, Puerto Vallarta<br \/>\nThis beautiful development is perfect for those who wish to live in an environment surrounded by mountains and the sea, while enjoying all the services offered by a city like Puerto Vallarta, Jalisco.<\/p>\n<p>This unit features three bedrooms and three full bathrooms, with two of the bedrooms including en-suite bathrooms and walk-in closets. It also includes a living room, kitchen, dining area, service room, and two terraces.<\/p>\n<p>It boasts a prime location with 34 apartments, 7 floors with an elevator, parking, storage units, 4 commercial spaces, 24-hour security, a Roof Garden, Kids&#8217; Playroom, Gym, Sky Bar, and stunning views of the bay.<\/p>\n<h3>Features<\/h3>\n<ul>\n<li>3 Bedrooms<\/li>\n<li>3 Bathrooms<\/li>\n<li>124.74 m\u00b2 (1,342.70 sqft) of construction<\/li>\n<li>Living Room<\/li>\n<li>Dining Room<\/li>\n<li>Kitchen<\/li>\n<li>Service Room<\/li>\n<li>Parking Space<\/li>\n<li>Terraces<\/li>\n<\/ul>\n<h3>Amenities<\/h3>\n<ul>\n<li>Roof Garden<\/li>\n<li>Sky Bar<\/li>\n<li>Swimming Pool<\/li>\n<li>Fire Pit<\/li>\n<li>Kids&#8217; Playroom<\/li>\n<li>Gym<\/li>\n<li>24\/7 Security<\/li>\n<li>Elevator<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Explore Unit 404, Prototype &#8220;A&#8221; at the Timone Development, located in Versalles, Puerto Vallarta This beautiful development is perfect for those who wish to live in an environment surrounded by mountains and the sea, while enjoying all the services offered by a city like Puerto Vallarta, Jalisco. This unit features three bedrooms and three full&#8230;<\/p>\n","protected":false},"author":3,"featured_media":9776,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","property-features":[172,160,157,59,158,60,45,178],"property-types":[],"property-cities":[124,154],"property-statuses":[84],"class_list":["post-9826","property","type-property","status-publish","has-post-thumbnail","hentry","property-feature-air-conditioning","property-feature-elevator","property-feature-gimnasio","property-feature-pool","property-feature-roof-garden","property-feature-seguridad-privada","property-feature-swimming-pool","property-feature-terraza","property-city-puerto-vallarta","property-city-versalles","property-status-en-venta"],"property_meta":{"REAL_HOMES_property_price":"7649308","REAL_HOMES_property_old_price":"","REAL_HOMES_property_price_prefix":"","REAL_HOMES_property_price_postfix":"","REAL_HOMES_property_size":"124.74","REAL_HOMES_property_size_postfix":"1,342.70","REAL_HOMES_property_lot_size":"","REAL_HOMES_property_lot_size_postfix":"","REAL_HOMES_property_bedrooms":"3","REAL_HOMES_property_bathrooms":"3","REAL_HOMES_property_garage":"1","REAL_HOMES_property_id":"","REAL_HOMES_property_year_built":"","REAL_HOMES_featured":"0","REAL_HOMES_additional_details_list":[],"REAL_HOMES_property_location":{"latitude":"25.7308309","longitude":"-80.444149","zoom":"15"},"REAL_HOMES_property_address":"Viena, Puerto Vallarta, Regi\u00f3n Costa Norte, Jalisco, 48300, M\u00e9xico","REAL_HOMES_property_map":"0","REAL_HOMES_property_images":[{"width":150,"height":150,"file":"2024\/11\/MODELO-A.jpg","filesize":193434,"sizes":{"medium":{"file":"MODELO-A-300x169.jpg","width":300,"height":169,"mime-type":"image\/jpeg","filesize":6640,"url":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/11\/MODELO-A-300x169.jpg"},"large":{"file":"MODELO-A-1024x576.jpg","width":1024,"height":576,"mime-type":"image\/jpeg","filesize":42363,"url":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/11\/MODELO-A-1024x576.jpg"},"thumbnail":{"file":"MODELO-A-150x150.jpg","width":150,"height":150,"mime-type":"image\/jpeg","filesize":5272,"url":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/11\/MODELO-A-150x150.jpg"},"medium_large":{"file":"MODELO-A-768x432.jpg","width":768,"height":432,"mime-type":"image\/jpeg","filesize":27542,"url":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/11\/MODELO-A-768x432.jpg"},"post-thumbnail":{"file":"MODELO-A-150x84.jpg","width":150,"height":84,"mime-type":"image\/jpeg","filesize":2551,"url":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/11\/MODELO-A-150x84.jpg"},"modern-property-child-slider":{"file":"MODELO-A-680x510.jpg","width":680,"height":510,"mime-type":"image\/jpeg","filesize":33736,"url":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/11\/MODELO-A-680x510.jpg"},"property-thumb-image":{"file":"MODELO-A-488x326.jpg","width":488,"height":326,"mime-type":"image\/jpeg","filesize":17363,"url":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/11\/MODELO-A-488x326.jpg"},"property-detail-video-image":{"file":"MODELO-A-818x417.jpg","width":818,"height":417,"mime-type":"image\/jpeg","filesize":29829,"url":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/11\/MODELO-A-818x417.jpg"},"agent-image":{"file":"MODELO-A-210x210.jpg","width":210,"height":210,"mime-type":"image\/jpeg","filesize":8704,"url":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/11\/MODELO-A-210x210.jpg"},"partners-logo":{"file":"MODELO-A-600x720.jpg","width":600,"height":720,"mime-type":"image\/jpeg","filesize":57232,"url":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/11\/MODELO-A-600x720.jpg"},"post-featured-image":{"file":"MODELO-A-1240x720.jpg","width":1240,"height":720,"mime-type":"image\/jpeg","filesize":65754,"url":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/11\/MODELO-A-1240x720.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]},"ID":"9790","name":"MODELO-A.jpg","path":"\/home\/casaqpta\/casaopcion.com\/en\/wp-content\/uploads\/2024\/11\/MODELO-A.jpg","url":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/11\/MODELO-A-150x150.jpg","full_url":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/11\/MODELO-A.jpg","title":"MODELO A","caption":"","description":"","alt":"","srcset":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/11\/MODELO-A-150x150.jpg 150w, https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/11\/MODELO-A-210x210.jpg 210w"},{"width":150,"height":150,"file":"2024\/10\/timone-puerto-vallarta-versalles-desarrollo-9-3.jpg","filesize":690761,"sizes":{"medium":{"file":"timone-puerto-vallarta-versalles-desarrollo-9-3-300x169.jpg","width":300,"height":169,"mime-type":"image\/jpeg","filesize":11125,"url":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/10\/timone-puerto-vallarta-versalles-desarrollo-9-3-300x169.jpg"},"large":{"file":"timone-puerto-vallarta-versalles-desarrollo-9-3-1024x576.jpg","width":1024,"height":576,"mime-type":"image\/jpeg","filesize":87518,"url":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/10\/timone-puerto-vallarta-versalles-desarrollo-9-3-1024x576.jpg"},"thumbnail":{"file":"timone-puerto-vallarta-versalles-desarrollo-9-3-150x150.jpg","width":150,"height":150,"mime-type":"image\/jpeg","filesize":5694,"url":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/10\/timone-puerto-vallarta-versalles-desarrollo-9-3-150x150.jpg"},"medium_large":{"file":"timone-puerto-vallarta-versalles-desarrollo-9-3-768x432.jpg","width":768,"height":432,"mime-type":"image\/jpeg","filesize":53106,"url":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/10\/timone-puerto-vallarta-versalles-desarrollo-9-3-768x432.jpg"},"post-thumbnail":{"file":"timone-puerto-vallarta-versalles-desarrollo-9-3-150x84.jpg","width":150,"height":84,"mime-type":"image\/jpeg","filesize":4067,"url":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/10\/timone-puerto-vallarta-versalles-desarrollo-9-3-150x84.jpg"},"modern-property-child-slider":{"file":"timone-puerto-vallarta-versalles-desarrollo-9-3-680x510.jpg","width":680,"height":510,"mime-type":"image\/jpeg","filesize":55656,"url":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/10\/timone-puerto-vallarta-versalles-desarrollo-9-3-680x510.jpg"},"property-thumb-image":{"file":"timone-puerto-vallarta-versalles-desarrollo-9-3-488x326.jpg","width":488,"height":326,"mime-type":"image\/jpeg","filesize":27605,"url":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/10\/timone-puerto-vallarta-versalles-desarrollo-9-3-488x326.jpg"},"property-detail-video-image":{"file":"timone-puerto-vallarta-versalles-desarrollo-9-3-818x417.jpg","width":818,"height":417,"mime-type":"image\/jpeg","filesize":54573,"url":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/10\/timone-puerto-vallarta-versalles-desarrollo-9-3-818x417.jpg"},"agent-image":{"file":"timone-puerto-vallarta-versalles-desarrollo-9-3-210x210.jpg","width":210,"height":210,"mime-type":"image\/jpeg","filesize":10002,"url":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/10\/timone-puerto-vallarta-versalles-desarrollo-9-3-210x210.jpg"},"partners-logo":{"file":"timone-puerto-vallarta-versalles-desarrollo-9-3-600x720.jpg","width":600,"height":720,"mime-type":"image\/jpeg","filesize":74731,"url":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/10\/timone-puerto-vallarta-versalles-desarrollo-9-3-600x720.jpg"},"post-featured-image":{"file":"timone-puerto-vallarta-versalles-desarrollo-9-3-1240x720.jpg","width":1240,"height":720,"mime-type":"image\/jpeg","filesize":139304,"url":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/10\/timone-puerto-vallarta-versalles-desarrollo-9-3-1240x720.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]},"ID":"9769","name":"timone-puerto-vallarta-versalles-desarrollo-9-3.jpg","path":"\/home\/casaqpta\/casaopcion.com\/en\/wp-content\/uploads\/2024\/10\/timone-puerto-vallarta-versalles-desarrollo-9-3.jpg","url":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/10\/timone-puerto-vallarta-versalles-desarrollo-9-3-150x150.jpg","full_url":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/10\/timone-puerto-vallarta-versalles-desarrollo-9-3.jpg","title":"timone-puerto-vallarta-versalles-desarrollo-9","caption":"","description":"","alt":"","srcset":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/10\/timone-puerto-vallarta-versalles-desarrollo-9-3-150x150.jpg 150w, https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/10\/timone-puerto-vallarta-versalles-desarrollo-9-3-210x210.jpg 210w"},{"width":150,"height":150,"file":"2024\/10\/timone-puerto-vallarta-versalles-desarrollo-1-3.jpg","filesize":1219412,"sizes":{"medium":{"file":"timone-puerto-vallarta-versalles-desarrollo-1-3-300x169.jpg","width":300,"height":169,"mime-type":"image\/jpeg","filesize":19707,"url":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/10\/timone-puerto-vallarta-versalles-desarrollo-1-3-300x169.jpg"},"large":{"file":"timone-puerto-vallarta-versalles-desarrollo-1-3-1024x576.jpg","width":1024,"height":576,"mime-type":"image\/jpeg","filesize":170969,"url":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/10\/timone-puerto-vallarta-versalles-desarrollo-1-3-1024x576.jpg"},"thumbnail":{"file":"timone-puerto-vallarta-versalles-desarrollo-1-3-150x150.jpg","width":150,"height":150,"mime-type":"image\/jpeg","filesize":10290,"url":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/10\/timone-puerto-vallarta-versalles-desarrollo-1-3-150x150.jpg"},"medium_large":{"file":"timone-puerto-vallarta-versalles-desarrollo-1-3-768x432.jpg","width":768,"height":432,"mime-type":"image\/jpeg","filesize":105665,"url":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/10\/timone-puerto-vallarta-versalles-desarrollo-1-3-768x432.jpg"},"post-thumbnail":{"file":"timone-puerto-vallarta-versalles-desarrollo-1-3-150x84.jpg","width":150,"height":84,"mime-type":"image\/jpeg","filesize":6019,"url":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/10\/timone-puerto-vallarta-versalles-desarrollo-1-3-150x84.jpg"},"modern-property-child-slider":{"file":"timone-puerto-vallarta-versalles-desarrollo-1-3-680x510.jpg","width":680,"height":510,"mime-type":"image\/jpeg","filesize":110457,"url":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/10\/timone-puerto-vallarta-versalles-desarrollo-1-3-680x510.jpg"},"property-thumb-image":{"file":"timone-puerto-vallarta-versalles-desarrollo-1-3-488x326.jpg","width":488,"height":326,"mime-type":"image\/jpeg","filesize":56010,"url":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/10\/timone-puerto-vallarta-versalles-desarrollo-1-3-488x326.jpg"},"property-detail-video-image":{"file":"timone-puerto-vallarta-versalles-desarrollo-1-3-818x417.jpg","width":818,"height":417,"mime-type":"image\/jpeg","filesize":106601,"url":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/10\/timone-puerto-vallarta-versalles-desarrollo-1-3-818x417.jpg"},"agent-image":{"file":"timone-puerto-vallarta-versalles-desarrollo-1-3-210x210.jpg","width":210,"height":210,"mime-type":"image\/jpeg","filesize":18660,"url":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/10\/timone-puerto-vallarta-versalles-desarrollo-1-3-210x210.jpg"},"partners-logo":{"file":"timone-puerto-vallarta-versalles-desarrollo-1-3-600x720.jpg","width":600,"height":720,"mime-type":"image\/jpeg","filesize":143392,"url":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/10\/timone-puerto-vallarta-versalles-desarrollo-1-3-600x720.jpg"},"post-featured-image":{"file":"timone-puerto-vallarta-versalles-desarrollo-1-3-1240x720.jpg","width":1240,"height":720,"mime-type":"image\/jpeg","filesize":275208,"url":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/10\/timone-puerto-vallarta-versalles-desarrollo-1-3-1240x720.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]},"ID":"9761","name":"timone-puerto-vallarta-versalles-desarrollo-1-3.jpg","path":"\/home\/casaqpta\/casaopcion.com\/en\/wp-content\/uploads\/2024\/10\/timone-puerto-vallarta-versalles-desarrollo-1-3.jpg","url":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/10\/timone-puerto-vallarta-versalles-desarrollo-1-3-150x150.jpg","full_url":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/10\/timone-puerto-vallarta-versalles-desarrollo-1-3.jpg","title":"timone-puerto-vallarta-versalles-desarrollo-1","caption":"","description":"","alt":"","srcset":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/10\/timone-puerto-vallarta-versalles-desarrollo-1-3-150x150.jpg 150w, https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/10\/timone-puerto-vallarta-versalles-desarrollo-1-3-210x210.jpg 210w"},{"width":150,"height":150,"file":"2024\/10\/timone-puerto-vallarta-versalles-desarrollo-8-3.jpg","filesize":653188,"sizes":{"medium":{"file":"timone-puerto-vallarta-versalles-desarrollo-8-3-300x169.jpg","width":300,"height":169,"mime-type":"image\/jpeg","filesize":13281,"url":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/10\/timone-puerto-vallarta-versalles-desarrollo-8-3-300x169.jpg"},"large":{"file":"timone-puerto-vallarta-versalles-desarrollo-8-3-1024x576.jpg","width":1024,"height":576,"mime-type":"image\/jpeg","filesize":97111,"url":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/10\/timone-puerto-vallarta-versalles-desarrollo-8-3-1024x576.jpg"},"thumbnail":{"file":"timone-puerto-vallarta-versalles-desarrollo-8-3-150x150.jpg","width":150,"height":150,"mime-type":"image\/jpeg","filesize":6319,"url":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/10\/timone-puerto-vallarta-versalles-desarrollo-8-3-150x150.jpg"},"medium_large":{"file":"timone-puerto-vallarta-versalles-desarrollo-8-3-768x432.jpg","width":768,"height":432,"mime-type":"image\/jpeg","filesize":60808,"url":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/10\/timone-puerto-vallarta-versalles-desarrollo-8-3-768x432.jpg"},"post-thumbnail":{"file":"timone-puerto-vallarta-versalles-desarrollo-8-3-150x84.jpg","width":150,"height":84,"mime-type":"image\/jpeg","filesize":4664,"url":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/10\/timone-puerto-vallarta-versalles-desarrollo-8-3-150x84.jpg"},"modern-property-child-slider":{"file":"timone-puerto-vallarta-versalles-desarrollo-8-3-680x510.jpg","width":680,"height":510,"mime-type":"image\/jpeg","filesize":59694,"url":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/10\/timone-puerto-vallarta-versalles-desarrollo-8-3-680x510.jpg"},"property-thumb-image":{"file":"timone-puerto-vallarta-versalles-desarrollo-8-3-488x326.jpg","width":488,"height":326,"mime-type":"image\/jpeg","filesize":31171,"url":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/10\/timone-puerto-vallarta-versalles-desarrollo-8-3-488x326.jpg"},"property-detail-video-image":{"file":"timone-puerto-vallarta-versalles-desarrollo-8-3-818x417.jpg","width":818,"height":417,"mime-type":"image\/jpeg","filesize":62957,"url":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/10\/timone-puerto-vallarta-versalles-desarrollo-8-3-818x417.jpg"},"agent-image":{"file":"timone-puerto-vallarta-versalles-desarrollo-8-3-210x210.jpg","width":210,"height":210,"mime-type":"image\/jpeg","filesize":10818,"url":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/10\/timone-puerto-vallarta-versalles-desarrollo-8-3-210x210.jpg"},"partners-logo":{"file":"timone-puerto-vallarta-versalles-desarrollo-8-3-600x720.jpg","width":600,"height":720,"mime-type":"image\/jpeg","filesize":79178,"url":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/10\/timone-puerto-vallarta-versalles-desarrollo-8-3-600x720.jpg"},"post-featured-image":{"file":"timone-puerto-vallarta-versalles-desarrollo-8-3-1240x720.jpg","width":1240,"height":720,"mime-type":"image\/jpeg","filesize":151941,"url":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/10\/timone-puerto-vallarta-versalles-desarrollo-8-3-1240x720.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]},"ID":"9768","name":"timone-puerto-vallarta-versalles-desarrollo-8-3.jpg","path":"\/home\/casaqpta\/casaopcion.com\/en\/wp-content\/uploads\/2024\/10\/timone-puerto-vallarta-versalles-desarrollo-8-3.jpg","url":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/10\/timone-puerto-vallarta-versalles-desarrollo-8-3-150x150.jpg","full_url":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/10\/timone-puerto-vallarta-versalles-desarrollo-8-3.jpg","title":"timone-puerto-vallarta-versalles-desarrollo-8","caption":"","description":"","alt":"","srcset":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/10\/timone-puerto-vallarta-versalles-desarrollo-8-3-150x150.jpg 150w, https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/10\/timone-puerto-vallarta-versalles-desarrollo-8-3-210x210.jpg 210w"},{"width":150,"height":150,"file":"2024\/10\/timone-puerto-vallarta-versalles-desarrollo-7-3.jpg","filesize":668410,"sizes":{"medium":{"file":"timone-puerto-vallarta-versalles-desarrollo-7-3-300x169.jpg","width":300,"height":169,"mime-type":"image\/jpeg","filesize":12947,"url":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/10\/timone-puerto-vallarta-versalles-desarrollo-7-3-300x169.jpg"},"large":{"file":"timone-puerto-vallarta-versalles-desarrollo-7-3-1024x576.jpg","width":1024,"height":576,"mime-type":"image\/jpeg","filesize":94764,"url":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/10\/timone-puerto-vallarta-versalles-desarrollo-7-3-1024x576.jpg"},"thumbnail":{"file":"timone-puerto-vallarta-versalles-desarrollo-7-3-150x150.jpg","width":150,"height":150,"mime-type":"image\/jpeg","filesize":6211,"url":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/10\/timone-puerto-vallarta-versalles-desarrollo-7-3-150x150.jpg"},"medium_large":{"file":"timone-puerto-vallarta-versalles-desarrollo-7-3-768x432.jpg","width":768,"height":432,"mime-type":"image\/jpeg","filesize":59069,"url":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/10\/timone-puerto-vallarta-versalles-desarrollo-7-3-768x432.jpg"},"post-thumbnail":{"file":"timone-puerto-vallarta-versalles-desarrollo-7-3-150x84.jpg","width":150,"height":84,"mime-type":"image\/jpeg","filesize":4689,"url":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/10\/timone-puerto-vallarta-versalles-desarrollo-7-3-150x84.jpg"},"modern-property-child-slider":{"file":"timone-puerto-vallarta-versalles-desarrollo-7-3-680x510.jpg","width":680,"height":510,"mime-type":"image\/jpeg","filesize":58938,"url":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/10\/timone-puerto-vallarta-versalles-desarrollo-7-3-680x510.jpg"},"property-thumb-image":{"file":"timone-puerto-vallarta-versalles-desarrollo-7-3-488x326.jpg","width":488,"height":326,"mime-type":"image\/jpeg","filesize":32002,"url":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/10\/timone-puerto-vallarta-versalles-desarrollo-7-3-488x326.jpg"},"property-detail-video-image":{"file":"timone-puerto-vallarta-versalles-desarrollo-7-3-818x417.jpg","width":818,"height":417,"mime-type":"image\/jpeg","filesize":61586,"url":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/10\/timone-puerto-vallarta-versalles-desarrollo-7-3-818x417.jpg"},"agent-image":{"file":"timone-puerto-vallarta-versalles-desarrollo-7-3-210x210.jpg","width":210,"height":210,"mime-type":"image\/jpeg","filesize":10308,"url":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/10\/timone-puerto-vallarta-versalles-desarrollo-7-3-210x210.jpg"},"partners-logo":{"file":"timone-puerto-vallarta-versalles-desarrollo-7-3-600x720.jpg","width":600,"height":720,"mime-type":"image\/jpeg","filesize":70832,"url":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/10\/timone-puerto-vallarta-versalles-desarrollo-7-3-600x720.jpg"},"post-featured-image":{"file":"timone-puerto-vallarta-versalles-desarrollo-7-3-1240x720.jpg","width":1240,"height":720,"mime-type":"image\/jpeg","filesize":145992,"url":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/10\/timone-puerto-vallarta-versalles-desarrollo-7-3-1240x720.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]},"ID":"9767","name":"timone-puerto-vallarta-versalles-desarrollo-7-3.jpg","path":"\/home\/casaqpta\/casaopcion.com\/en\/wp-content\/uploads\/2024\/10\/timone-puerto-vallarta-versalles-desarrollo-7-3.jpg","url":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/10\/timone-puerto-vallarta-versalles-desarrollo-7-3-150x150.jpg","full_url":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/10\/timone-puerto-vallarta-versalles-desarrollo-7-3.jpg","title":"timone-puerto-vallarta-versalles-desarrollo-7","caption":"","description":"","alt":"","srcset":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/10\/timone-puerto-vallarta-versalles-desarrollo-7-3-150x150.jpg 150w, https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/10\/timone-puerto-vallarta-versalles-desarrollo-7-3-210x210.jpg 210w"},{"width":150,"height":150,"file":"2024\/10\/timone-puerto-vallarta-versalles-desarrollo-6-3.jpg","filesize":753396,"sizes":{"medium":{"file":"timone-puerto-vallarta-versalles-desarrollo-6-3-300x169.jpg","width":300,"height":169,"mime-type":"image\/jpeg","filesize":12883,"url":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/10\/timone-puerto-vallarta-versalles-desarrollo-6-3-300x169.jpg"},"large":{"file":"timone-puerto-vallarta-versalles-desarrollo-6-3-1024x576.jpg","width":1024,"height":576,"mime-type":"image\/jpeg","filesize":100658,"url":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/10\/timone-puerto-vallarta-versalles-desarrollo-6-3-1024x576.jpg"},"thumbnail":{"file":"timone-puerto-vallarta-versalles-desarrollo-6-3-150x150.jpg","width":150,"height":150,"mime-type":"image\/jpeg","filesize":6102,"url":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/10\/timone-puerto-vallarta-versalles-desarrollo-6-3-150x150.jpg"},"medium_large":{"file":"timone-puerto-vallarta-versalles-desarrollo-6-3-768x432.jpg","width":768,"height":432,"mime-type":"image\/jpeg","filesize":63227,"url":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/10\/timone-puerto-vallarta-versalles-desarrollo-6-3-768x432.jpg"},"post-thumbnail":{"file":"timone-puerto-vallarta-versalles-desarrollo-6-3-150x84.jpg","width":150,"height":84,"mime-type":"image\/jpeg","filesize":4606,"url":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/10\/timone-puerto-vallarta-versalles-desarrollo-6-3-150x84.jpg"},"modern-property-child-slider":{"file":"timone-puerto-vallarta-versalles-desarrollo-6-3-680x510.jpg","width":680,"height":510,"mime-type":"image\/jpeg","filesize":62445,"url":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/10\/timone-puerto-vallarta-versalles-desarrollo-6-3-680x510.jpg"},"property-thumb-image":{"file":"timone-puerto-vallarta-versalles-desarrollo-6-3-488x326.jpg","width":488,"height":326,"mime-type":"image\/jpeg","filesize":32992,"url":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/10\/timone-puerto-vallarta-versalles-desarrollo-6-3-488x326.jpg"},"property-detail-video-image":{"file":"timone-puerto-vallarta-versalles-desarrollo-6-3-818x417.jpg","width":818,"height":417,"mime-type":"image\/jpeg","filesize":65710,"url":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/10\/timone-puerto-vallarta-versalles-desarrollo-6-3-818x417.jpg"},"agent-image":{"file":"timone-puerto-vallarta-versalles-desarrollo-6-3-210x210.jpg","width":210,"height":210,"mime-type":"image\/jpeg","filesize":10338,"url":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/10\/timone-puerto-vallarta-versalles-desarrollo-6-3-210x210.jpg"},"partners-logo":{"file":"timone-puerto-vallarta-versalles-desarrollo-6-3-600x720.jpg","width":600,"height":720,"mime-type":"image\/jpeg","filesize":70028,"url":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/10\/timone-puerto-vallarta-versalles-desarrollo-6-3-600x720.jpg"},"post-featured-image":{"file":"timone-puerto-vallarta-versalles-desarrollo-6-3-1240x720.jpg","width":1240,"height":720,"mime-type":"image\/jpeg","filesize":156631,"url":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/10\/timone-puerto-vallarta-versalles-desarrollo-6-3-1240x720.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]},"ID":"9766","name":"timone-puerto-vallarta-versalles-desarrollo-6-3.jpg","path":"\/home\/casaqpta\/casaopcion.com\/en\/wp-content\/uploads\/2024\/10\/timone-puerto-vallarta-versalles-desarrollo-6-3.jpg","url":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/10\/timone-puerto-vallarta-versalles-desarrollo-6-3-150x150.jpg","full_url":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/10\/timone-puerto-vallarta-versalles-desarrollo-6-3.jpg","title":"timone-puerto-vallarta-versalles-desarrollo-6","caption":"","description":"","alt":"","srcset":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/10\/timone-puerto-vallarta-versalles-desarrollo-6-3-150x150.jpg 150w, https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/10\/timone-puerto-vallarta-versalles-desarrollo-6-3-210x210.jpg 210w"},{"width":150,"height":150,"file":"2024\/10\/timone-puerto-vallarta-versalles-desarrollo-5-3.jpg","filesize":727793,"sizes":{"medium":{"file":"timone-puerto-vallarta-versalles-desarrollo-5-3-300x169.jpg","width":300,"height":169,"mime-type":"image\/jpeg","filesize":13003,"url":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/10\/timone-puerto-vallarta-versalles-desarrollo-5-3-300x169.jpg"},"large":{"file":"timone-puerto-vallarta-versalles-desarrollo-5-3-1024x576.jpg","width":1024,"height":576,"mime-type":"image\/jpeg","filesize":102003,"url":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/10\/timone-puerto-vallarta-versalles-desarrollo-5-3-1024x576.jpg"},"thumbnail":{"file":"timone-puerto-vallarta-versalles-desarrollo-5-3-150x150.jpg","width":150,"height":150,"mime-type":"image\/jpeg","filesize":7491,"url":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/10\/timone-puerto-vallarta-versalles-desarrollo-5-3-150x150.jpg"},"medium_large":{"file":"timone-puerto-vallarta-versalles-desarrollo-5-3-768x432.jpg","width":768,"height":432,"mime-type":"image\/jpeg","filesize":62660,"url":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/10\/timone-puerto-vallarta-versalles-desarrollo-5-3-768x432.jpg"},"post-thumbnail":{"file":"timone-puerto-vallarta-versalles-desarrollo-5-3-150x84.jpg","width":150,"height":84,"mime-type":"image\/jpeg","filesize":4517,"url":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/10\/timone-puerto-vallarta-versalles-desarrollo-5-3-150x84.jpg"},"modern-property-child-slider":{"file":"timone-puerto-vallarta-versalles-desarrollo-5-3-680x510.jpg","width":680,"height":510,"mime-type":"image\/jpeg","filesize":68202,"url":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/10\/timone-puerto-vallarta-versalles-desarrollo-5-3-680x510.jpg"},"property-thumb-image":{"file":"timone-puerto-vallarta-versalles-desarrollo-5-3-488x326.jpg","width":488,"height":326,"mime-type":"image\/jpeg","filesize":34108,"url":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/10\/timone-puerto-vallarta-versalles-desarrollo-5-3-488x326.jpg"},"property-detail-video-image":{"file":"timone-puerto-vallarta-versalles-desarrollo-5-3-818x417.jpg","width":818,"height":417,"mime-type":"image\/jpeg","filesize":64257,"url":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/10\/timone-puerto-vallarta-versalles-desarrollo-5-3-818x417.jpg"},"agent-image":{"file":"timone-puerto-vallarta-versalles-desarrollo-5-3-210x210.jpg","width":210,"height":210,"mime-type":"image\/jpeg","filesize":12960,"url":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/10\/timone-puerto-vallarta-versalles-desarrollo-5-3-210x210.jpg"},"partners-logo":{"file":"timone-puerto-vallarta-versalles-desarrollo-5-3-600x720.jpg","width":600,"height":720,"mime-type":"image\/jpeg","filesize":91680,"url":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/10\/timone-puerto-vallarta-versalles-desarrollo-5-3-600x720.jpg"},"post-featured-image":{"file":"timone-puerto-vallarta-versalles-desarrollo-5-3-1240x720.jpg","width":1240,"height":720,"mime-type":"image\/jpeg","filesize":161679,"url":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/10\/timone-puerto-vallarta-versalles-desarrollo-5-3-1240x720.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]},"ID":"9765","name":"timone-puerto-vallarta-versalles-desarrollo-5-3.jpg","path":"\/home\/casaqpta\/casaopcion.com\/en\/wp-content\/uploads\/2024\/10\/timone-puerto-vallarta-versalles-desarrollo-5-3.jpg","url":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/10\/timone-puerto-vallarta-versalles-desarrollo-5-3-150x150.jpg","full_url":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/10\/timone-puerto-vallarta-versalles-desarrollo-5-3.jpg","title":"timone-puerto-vallarta-versalles-desarrollo-5","caption":"","description":"","alt":"","srcset":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/10\/timone-puerto-vallarta-versalles-desarrollo-5-3-150x150.jpg 150w, https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/10\/timone-puerto-vallarta-versalles-desarrollo-5-3-210x210.jpg 210w"},{"width":150,"height":150,"file":"2024\/10\/timone-puerto-vallarta-versalles-desarrollo-4-3.jpg","filesize":696995,"sizes":{"medium":{"file":"timone-puerto-vallarta-versalles-desarrollo-4-3-300x169.jpg","width":300,"height":169,"mime-type":"image\/jpeg","filesize":10703,"url":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/10\/timone-puerto-vallarta-versalles-desarrollo-4-3-300x169.jpg"},"large":{"file":"timone-puerto-vallarta-versalles-desarrollo-4-3-1024x576.jpg","width":1024,"height":576,"mime-type":"image\/jpeg","filesize":104153,"url":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/10\/timone-puerto-vallarta-versalles-desarrollo-4-3-1024x576.jpg"},"thumbnail":{"file":"timone-puerto-vallarta-versalles-desarrollo-4-3-150x150.jpg","width":150,"height":150,"mime-type":"image\/jpeg","filesize":5301,"url":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/10\/timone-puerto-vallarta-versalles-desarrollo-4-3-150x150.jpg"},"medium_large":{"file":"timone-puerto-vallarta-versalles-desarrollo-4-3-768x432.jpg","width":768,"height":432,"mime-type":"image\/jpeg","filesize":60562,"url":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/10\/timone-puerto-vallarta-versalles-desarrollo-4-3-768x432.jpg"},"post-thumbnail":{"file":"timone-puerto-vallarta-versalles-desarrollo-4-3-150x84.jpg","width":150,"height":84,"mime-type":"image\/jpeg","filesize":3725,"url":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/10\/timone-puerto-vallarta-versalles-desarrollo-4-3-150x84.jpg"},"modern-property-child-slider":{"file":"timone-puerto-vallarta-versalles-desarrollo-4-3-680x510.jpg","width":680,"height":510,"mime-type":"image\/jpeg","filesize":65448,"url":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/10\/timone-puerto-vallarta-versalles-desarrollo-4-3-680x510.jpg"},"property-thumb-image":{"file":"timone-puerto-vallarta-versalles-desarrollo-4-3-488x326.jpg","width":488,"height":326,"mime-type":"image\/jpeg","filesize":30589,"url":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/10\/timone-puerto-vallarta-versalles-desarrollo-4-3-488x326.jpg"},"property-detail-video-image":{"file":"timone-puerto-vallarta-versalles-desarrollo-4-3-818x417.jpg","width":818,"height":417,"mime-type":"image\/jpeg","filesize":62103,"url":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/10\/timone-puerto-vallarta-versalles-desarrollo-4-3-818x417.jpg"},"agent-image":{"file":"timone-puerto-vallarta-versalles-desarrollo-4-3-210x210.jpg","width":210,"height":210,"mime-type":"image\/jpeg","filesize":9926,"url":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/10\/timone-puerto-vallarta-versalles-desarrollo-4-3-210x210.jpg"},"partners-logo":{"file":"timone-puerto-vallarta-versalles-desarrollo-4-3-600x720.jpg","width":600,"height":720,"mime-type":"image\/jpeg","filesize":94359,"url":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/10\/timone-puerto-vallarta-versalles-desarrollo-4-3-600x720.jpg"},"post-featured-image":{"file":"timone-puerto-vallarta-versalles-desarrollo-4-3-1240x720.jpg","width":1240,"height":720,"mime-type":"image\/jpeg","filesize":169375,"url":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/10\/timone-puerto-vallarta-versalles-desarrollo-4-3-1240x720.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]},"ID":"9764","name":"timone-puerto-vallarta-versalles-desarrollo-4-3.jpg","path":"\/home\/casaqpta\/casaopcion.com\/en\/wp-content\/uploads\/2024\/10\/timone-puerto-vallarta-versalles-desarrollo-4-3.jpg","url":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/10\/timone-puerto-vallarta-versalles-desarrollo-4-3-150x150.jpg","full_url":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/10\/timone-puerto-vallarta-versalles-desarrollo-4-3.jpg","title":"timone-puerto-vallarta-versalles-desarrollo-4","caption":"","description":"","alt":"","srcset":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/10\/timone-puerto-vallarta-versalles-desarrollo-4-3-150x150.jpg 150w, https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/10\/timone-puerto-vallarta-versalles-desarrollo-4-3-210x210.jpg 210w"},{"width":150,"height":150,"file":"2024\/10\/timone-puerto-vallarta-versalles-desarrollo-3-4.jpg","filesize":919961,"sizes":{"medium":{"file":"timone-puerto-vallarta-versalles-desarrollo-3-4-300x169.jpg","width":300,"height":169,"mime-type":"image\/jpeg","filesize":17704,"url":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/10\/timone-puerto-vallarta-versalles-desarrollo-3-4-300x169.jpg"},"large":{"file":"timone-puerto-vallarta-versalles-desarrollo-3-4-1024x576.jpg","width":1024,"height":576,"mime-type":"image\/jpeg","filesize":140996,"url":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/10\/timone-puerto-vallarta-versalles-desarrollo-3-4-1024x576.jpg"},"thumbnail":{"file":"timone-puerto-vallarta-versalles-desarrollo-3-4-150x150.jpg","width":150,"height":150,"mime-type":"image\/jpeg","filesize":9580,"url":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/10\/timone-puerto-vallarta-versalles-desarrollo-3-4-150x150.jpg"},"medium_large":{"file":"timone-puerto-vallarta-versalles-desarrollo-3-4-768x432.jpg","width":768,"height":432,"mime-type":"image\/jpeg","filesize":88389,"url":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/10\/timone-puerto-vallarta-versalles-desarrollo-3-4-768x432.jpg"},"post-thumbnail":{"file":"timone-puerto-vallarta-versalles-desarrollo-3-4-150x84.jpg","width":150,"height":84,"mime-type":"image\/jpeg","filesize":5688,"url":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/10\/timone-puerto-vallarta-versalles-desarrollo-3-4-150x84.jpg"},"modern-property-child-slider":{"file":"timone-puerto-vallarta-versalles-desarrollo-3-4-680x510.jpg","width":680,"height":510,"mime-type":"image\/jpeg","filesize":95267,"url":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/10\/timone-puerto-vallarta-versalles-desarrollo-3-4-680x510.jpg"},"property-thumb-image":{"file":"timone-puerto-vallarta-versalles-desarrollo-3-4-488x326.jpg","width":488,"height":326,"mime-type":"image\/jpeg","filesize":48548,"url":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/10\/timone-puerto-vallarta-versalles-desarrollo-3-4-488x326.jpg"},"property-detail-video-image":{"file":"timone-puerto-vallarta-versalles-desarrollo-3-4-818x417.jpg","width":818,"height":417,"mime-type":"image\/jpeg","filesize":91480,"url":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/10\/timone-puerto-vallarta-versalles-desarrollo-3-4-818x417.jpg"},"agent-image":{"file":"timone-puerto-vallarta-versalles-desarrollo-3-4-210x210.jpg","width":210,"height":210,"mime-type":"image\/jpeg","filesize":17099,"url":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/10\/timone-puerto-vallarta-versalles-desarrollo-3-4-210x210.jpg"},"partners-logo":{"file":"timone-puerto-vallarta-versalles-desarrollo-3-4-600x720.jpg","width":600,"height":720,"mime-type":"image\/jpeg","filesize":111053,"url":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/10\/timone-puerto-vallarta-versalles-desarrollo-3-4-600x720.jpg"},"post-featured-image":{"file":"timone-puerto-vallarta-versalles-desarrollo-3-4-1240x720.jpg","width":1240,"height":720,"mime-type":"image\/jpeg","filesize":217895,"url":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/10\/timone-puerto-vallarta-versalles-desarrollo-3-4-1240x720.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]},"ID":"9763","name":"timone-puerto-vallarta-versalles-desarrollo-3-4.jpg","path":"\/home\/casaqpta\/casaopcion.com\/en\/wp-content\/uploads\/2024\/10\/timone-puerto-vallarta-versalles-desarrollo-3-4.jpg","url":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/10\/timone-puerto-vallarta-versalles-desarrollo-3-4-150x150.jpg","full_url":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/10\/timone-puerto-vallarta-versalles-desarrollo-3-4.jpg","title":"timone-puerto-vallarta-versalles-desarrollo-3","caption":"","description":"","alt":"","srcset":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/10\/timone-puerto-vallarta-versalles-desarrollo-3-4-150x150.jpg 150w, https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/10\/timone-puerto-vallarta-versalles-desarrollo-3-4-210x210.jpg 210w"},{"width":150,"height":150,"file":"2024\/10\/timone-puerto-vallarta-versalles-desarrollo-2-3.jpg","filesize":1142742,"sizes":{"medium":{"file":"timone-puerto-vallarta-versalles-desarrollo-2-3-300x169.jpg","width":300,"height":169,"mime-type":"image\/jpeg","filesize":19895,"url":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/10\/timone-puerto-vallarta-versalles-desarrollo-2-3-300x169.jpg"},"large":{"file":"timone-puerto-vallarta-versalles-desarrollo-2-3-1024x576.jpg","width":1024,"height":576,"mime-type":"image\/jpeg","filesize":178283,"url":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/10\/timone-puerto-vallarta-versalles-desarrollo-2-3-1024x576.jpg"},"thumbnail":{"file":"timone-puerto-vallarta-versalles-desarrollo-2-3-150x150.jpg","width":150,"height":150,"mime-type":"image\/jpeg","filesize":9964,"url":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/10\/timone-puerto-vallarta-versalles-desarrollo-2-3-150x150.jpg"},"medium_large":{"file":"timone-puerto-vallarta-versalles-desarrollo-2-3-768x432.jpg","width":768,"height":432,"mime-type":"image\/jpeg","filesize":109615,"url":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/10\/timone-puerto-vallarta-versalles-desarrollo-2-3-768x432.jpg"},"post-thumbnail":{"file":"timone-puerto-vallarta-versalles-desarrollo-2-3-150x84.jpg","width":150,"height":84,"mime-type":"image\/jpeg","filesize":6036,"url":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/10\/timone-puerto-vallarta-versalles-desarrollo-2-3-150x84.jpg"},"modern-property-child-slider":{"file":"timone-puerto-vallarta-versalles-desarrollo-2-3-680x510.jpg","width":680,"height":510,"mime-type":"image\/jpeg","filesize":111182,"url":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/10\/timone-puerto-vallarta-versalles-desarrollo-2-3-680x510.jpg"},"property-thumb-image":{"file":"timone-puerto-vallarta-versalles-desarrollo-2-3-488x326.jpg","width":488,"height":326,"mime-type":"image\/jpeg","filesize":56876,"url":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/10\/timone-puerto-vallarta-versalles-desarrollo-2-3-488x326.jpg"},"property-detail-video-image":{"file":"timone-puerto-vallarta-versalles-desarrollo-2-3-818x417.jpg","width":818,"height":417,"mime-type":"image\/jpeg","filesize":114094,"url":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/10\/timone-puerto-vallarta-versalles-desarrollo-2-3-818x417.jpg"},"agent-image":{"file":"timone-puerto-vallarta-versalles-desarrollo-2-3-210x210.jpg","width":210,"height":210,"mime-type":"image\/jpeg","filesize":18535,"url":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/10\/timone-puerto-vallarta-versalles-desarrollo-2-3-210x210.jpg"},"partners-logo":{"file":"timone-puerto-vallarta-versalles-desarrollo-2-3-600x720.jpg","width":600,"height":720,"mime-type":"image\/jpeg","filesize":140461,"url":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/10\/timone-puerto-vallarta-versalles-desarrollo-2-3-600x720.jpg"},"post-featured-image":{"file":"timone-puerto-vallarta-versalles-desarrollo-2-3-1240x720.jpg","width":1240,"height":720,"mime-type":"image\/jpeg","filesize":282657,"url":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/10\/timone-puerto-vallarta-versalles-desarrollo-2-3-1240x720.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]},"ID":"9762","name":"timone-puerto-vallarta-versalles-desarrollo-2-3.jpg","path":"\/home\/casaqpta\/casaopcion.com\/en\/wp-content\/uploads\/2024\/10\/timone-puerto-vallarta-versalles-desarrollo-2-3.jpg","url":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/10\/timone-puerto-vallarta-versalles-desarrollo-2-3-150x150.jpg","full_url":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/10\/timone-puerto-vallarta-versalles-desarrollo-2-3.jpg","title":"timone-puerto-vallarta-versalles-desarrollo-2","caption":"","description":"","alt":"","srcset":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/10\/timone-puerto-vallarta-versalles-desarrollo-2-3-150x150.jpg 150w, https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/10\/timone-puerto-vallarta-versalles-desarrollo-2-3-210x210.jpg 210w"},{"width":150,"height":150,"file":"2024\/11\/U-404.jpg","filesize":165776,"sizes":{"medium":{"file":"U-404-300x169.jpg","width":300,"height":169,"mime-type":"image\/jpeg","filesize":7075,"url":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/11\/U-404-300x169.jpg"},"large":{"file":"U-404-1024x576.jpg","width":1024,"height":576,"mime-type":"image\/jpeg","filesize":50734,"url":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/11\/U-404-1024x576.jpg"},"thumbnail":{"file":"U-404-150x150.jpg","width":150,"height":150,"mime-type":"image\/jpeg","filesize":5778,"url":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/11\/U-404-150x150.jpg"},"medium_large":{"file":"U-404-768x432.jpg","width":768,"height":432,"mime-type":"image\/jpeg","filesize":31900,"url":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/11\/U-404-768x432.jpg"},"post-thumbnail":{"file":"U-404-150x84.jpg","width":150,"height":84,"mime-type":"image\/jpeg","filesize":2745,"url":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/11\/U-404-150x84.jpg"},"modern-property-child-slider":{"file":"U-404-680x510.jpg","width":680,"height":510,"mime-type":"image\/jpeg","filesize":39479,"url":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/11\/U-404-680x510.jpg"},"property-thumb-image":{"file":"U-404-488x326.jpg","width":488,"height":326,"mime-type":"image\/jpeg","filesize":20289,"url":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/11\/U-404-488x326.jpg"},"property-detail-video-image":{"file":"U-404-818x417.jpg","width":818,"height":417,"mime-type":"image\/jpeg","filesize":33121,"url":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/11\/U-404-818x417.jpg"},"agent-image":{"file":"U-404-210x210.jpg","width":210,"height":210,"mime-type":"image\/jpeg","filesize":9538,"url":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/11\/U-404-210x210.jpg"},"partners-logo":{"file":"U-404-600x720.jpg","width":600,"height":720,"mime-type":"image\/jpeg","filesize":69438,"url":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/11\/U-404-600x720.jpg"},"post-featured-image":{"file":"U-404-1240x720.jpg","width":1240,"height":720,"mime-type":"image\/jpeg","filesize":76638,"url":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/11\/U-404-1240x720.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]},"ID":"9827","name":"U-404.jpg","path":"\/home\/casaqpta\/casaopcion.com\/en\/wp-content\/uploads\/2024\/11\/U-404.jpg","url":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/11\/U-404-150x150.jpg","full_url":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/11\/U-404.jpg","title":"U-404","caption":"","description":"","alt":"","srcset":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/11\/U-404-150x150.jpg 150w, https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/11\/U-404-210x210.jpg 210w"}],"REAL_HOMES_change_gallery_slider_type":"0","REAL_HOMES_gallery_slider_type":"thumb-on-right","inspiry_floor_plans":[],"inspiry_video_group":[],"REAL_HOMES_360_virtual_tour":"","REAL_HOMES_tour_video_url":"","REAL_HOMES_tour_video_image":[],"REAL_HOMES_agent_display_option":"none","REAL_HOMES_agents":[],"REAL_HOMES_energy_class":"none","REAL_HOMES_energy_performance":"","REAL_HOMES_epc_current_rating":"","REAL_HOMES_epc_potential_rating":"","REAL_HOMES_sticky":"0","inspiry_property_label":"","inspiry_property_label_color":"","inspiry_property_tax":"0","inspiry_additional_fee":"0","REAL_HOMES_attachments":[],"inspiry_property_owner_name":"","inspiry_property_owner_contact":"","inspiry_property_owner_address":"","REAL_HOMES_property_private_note":"","inspiry_message_to_reviewer":"","REAL_HOMES_add_in_slider":"no","REAL_HOMES_slider_image":[],"REAL_HOMES_page_banner_image":[],"REAL_HOMES_hide_property_advance_search":"0","REAL_HOMES_custom_header_display":"default","REAL_HOMES_custom_header_position":"relative","REAL_HOMES_hide_advance_search":"0","REAL_HOMES_custom_search_form":"default","REAL_HOMES_search_form_margin_top":"","REAL_HOMES_search_form_margin_bottom":"","REAL_HOMES_custom_footer_display":"default"},"_links":{"self":[{"href":"https:\/\/casaopcion.com\/en\/wp-json\/wp\/v2\/properties\/9826","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/casaopcion.com\/en\/wp-json\/wp\/v2\/properties"}],"about":[{"href":"https:\/\/casaopcion.com\/en\/wp-json\/wp\/v2\/types\/property"}],"author":[{"embeddable":true,"href":"https:\/\/casaopcion.com\/en\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/casaopcion.com\/en\/wp-json\/wp\/v2\/comments?post=9826"}],"version-history":[{"count":1,"href":"https:\/\/casaopcion.com\/en\/wp-json\/wp\/v2\/properties\/9826\/revisions"}],"predecessor-version":[{"id":9828,"href":"https:\/\/casaopcion.com\/en\/wp-json\/wp\/v2\/properties\/9826\/revisions\/9828"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/casaopcion.com\/en\/wp-json\/wp\/v2\/media\/9776"}],"wp:attachment":[{"href":"https:\/\/casaopcion.com\/en\/wp-json\/wp\/v2\/media?parent=9826"}],"wp:term":[{"taxonomy":"property-feature","embeddable":true,"href":"https:\/\/casaopcion.com\/en\/wp-json\/wp\/v2\/property-features?post=9826"},{"taxonomy":"property-type","embeddable":true,"href":"https:\/\/casaopcion.com\/en\/wp-json\/wp\/v2\/property-types?post=9826"},{"taxonomy":"property-city","embeddable":true,"href":"https:\/\/casaopcion.com\/en\/wp-json\/wp\/v2\/property-cities?post=9826"},{"taxonomy":"property-status","embeddable":true,"href":"https:\/\/casaopcion.com\/en\/wp-json\/wp\/v2\/property-statuses?post=9826"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}