{"id":9509,"date":"2024-07-22T13:33:37","date_gmt":"2024-07-22T18:33:37","guid":{"rendered":"https:\/\/casaopcion.com\/en\/?post_type=property&#038;p=9509"},"modified":"2024-07-22T13:34:14","modified_gmt":"2024-07-22T18:34:14","slug":"bambu-d-110-torre-diamante-en-bambu-residencial","status":"publish","type":"property","link":"https:\/\/casaopcion.com\/en\/property\/bambu-d-110-torre-diamante-en-bambu-residencial\/","title":{"rendered":"Bamb\u00fa D-110"},"content":{"rendered":"<div class=\"flex-1 overflow-hidden\">\n<div class=\"h-full\">\n<div class=\"react-scroll-to-bottom--css-olbbb-79elbk h-full\">\n<div class=\"react-scroll-to-bottom--css-olbbb-1n7m0yu\">\n<div class=\"flex flex-col text-sm md:pb-9\">\n<div class=\"w-full text-token-text-primary\" dir=\"auto\" data-testid=\"conversation-turn-7\" data-scroll-anchor=\"true\">\n<div class=\"text-base py-[18px] px-3 md:px-4 m-auto md:px-5 lg:px-1 xl:px-5\">\n<div class=\"mx-auto flex flex-1 gap-4 text-base md:gap-5 lg:gap-6 md:max-w-3xl\">\n<div class=\"group\/conversation-turn relative flex w-full min-w-0 flex-col agent-turn\">\n<div class=\"flex-col gap-1 md:gap-3\">\n<div class=\"flex flex-grow flex-col max-w-full\">\n<div class=\"min-h-[20px] text-message flex w-full flex-col items-end gap-2 whitespace-pre-wrap break-words [.text-message+&amp;]:mt-5 overflow-x-auto\" dir=\"auto\" data-message-author-role=\"assistant\" data-message-id=\"bd8efcf2-484d-4b98-99cc-310b4d684482\">\n<div class=\"flex w-full flex-col gap-1 empty:hidden first:pt-[3px]\">\n<div class=\"markdown prose w-full break-words dark:prose-invert dark\">\n<p>Introducing <strong>Bamb\u00fa D-110<\/strong>, a beautiful residential development in an excellent location within Bamb\u00fa Residencial.<\/p>\n<p>Located in Torre Diamante at Bamb\u00fa Residencial, this stunning development is situated in Puerto Vallarta.<\/p>\n<p>This apartment offers a rear view, one bedroom, one full bathroom, living room, dining room, kitchen, service area, and a terrace with a beautiful view. It boasts 42.85 sqm of construction.<\/p>\n<p>Additionally, it features three bedrooms, two and a half bathrooms, living room, dining room, kitchen, and a patio. The development also includes common areas such as a pool and children&#8217;s play area.<\/p>\n<p>FEATURES<\/p>\n<ul>\n<li>42.85 sqm of construction<\/li>\n<li>1 bedroom<\/li>\n<li>1 bathroom<\/li>\n<\/ul>\n<p>AMENITIES:<\/p>\n<ul>\n<li>Pool Clubhouse<\/li>\n<li>Kids&#8217; play area<\/li>\n<li>\/7 security<\/li>\n<li>Barbecue area<\/li>\n<li>Security booth<\/li>\n<\/ul>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"mt-1 flex gap-3 empty:hidden -ml-2\">\n<div class=\"items-center justify-start rounded-xl p-1 flex\">\n<div class=\"flex items-center\"><\/div>\n<\/div>\n<\/div>\n<div class=\"pr-2 lg:pr-0\"><\/div>\n<div class=\"mt-3 w-full empty:hidden\">\n<div class=\"text-center\"><\/div>\n<\/div>\n<\/div>\n<div class=\"absolute\">\n<div class=\"flex items-center justify-center\"><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"md:pt-0 dark:border-white\/20 md:border-transparent md:dark:border-transparent w-full\">\n<div class=\"text-base px-3 md:px-4 m-auto md:px-5 lg:px-1 xl:px-5\">\n<div class=\"mx-auto flex flex-1 gap-4 text-base md:gap-5 lg:gap-6 md:max-w-3xl\">\n<form class=\"w-full\" aria-haspopup=\"dialog\" aria-expanded=\"false\" aria-controls=\"radix-:r4:\" data-state=\"closed\">\n<div class=\"relative flex h-full max-w-full flex-1 flex-col\">\n<div class=\"absolute bottom-full left-0 right-0 z-20\"><\/div>\n<div class=\"flex w-full items-center\">\n<div class=\"flex w-full flex-col gap-1.5 rounded-[26px] p-1.5 transition-colors bg-[#f4f4f4] dark:bg-token-main-surface-secondary\">\n<div class=\"flex items-end gap-1.5 md:gap-2\">\n<div class=\"flex min-w-0 flex-1 flex-col pl-4\"><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/form>\n<\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Introducing Bamb\u00fa D-110, a beautiful residential development in an excellent location within Bamb\u00fa Residencial. Located in Torre Diamante at Bamb\u00fa Residencial, this stunning development is situated in Puerto Vallarta. This apartment offers a rear view, one bedroom, one full bathroom, living room, dining room, kitchen, service area, and a terrace with a beautiful view. It&#8230;<\/p>\n","protected":false},"author":3,"featured_media":9517,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","property-features":[163,162,59,171,166,170],"property-types":[71,68,72],"property-cities":[124],"property-statuses":[84],"class_list":["post-9509","property","type-property","status-publish","has-post-thumbnail","hentry","property-feature-clubhouse","property-feature-green-spaces","property-feature-pool","property-feature-torre-diamante","property-feature-zona-grill","property-feature-zona-infantil","property-type-apartments","property-type-condos","property-type-developments","property-city-puerto-vallarta","property-status-en-venta"],"property_meta":{"REAL_HOMES_property_price":"2995000","REAL_HOMES_property_old_price":"","REAL_HOMES_property_price_prefix":"","REAL_HOMES_property_price_postfix":"","REAL_HOMES_property_size":"42.85","REAL_HOMES_property_size_postfix":"","REAL_HOMES_property_lot_size":"","REAL_HOMES_property_lot_size_postfix":"","REAL_HOMES_property_bedrooms":"1","REAL_HOMES_property_bathrooms":"1","REAL_HOMES_property_garage":"1","REAL_HOMES_property_id":"","REAL_HOMES_property_year_built":"","REAL_HOMES_featured":"0","REAL_HOMES_additional_details_list":[],"REAL_HOMES_property_location":{"latitude":"20.658206665498","longitude":"-105.22764301297","zoom":"16"},"REAL_HOMES_property_address":"Puerto Vallarta, Regi\u00f3n Costa Norte, Jalisco, 48300, M\u00e9xico","REAL_HOMES_property_map":"0","REAL_HOMES_property_images":[{"width":150,"height":150,"file":"2024\/07\/d-110-bambu-residencial-puerto-valalrta-1.jpg","filesize":221659,"sizes":{"medium":{"file":"d-110-bambu-residencial-puerto-valalrta-1-300x169.jpg","width":300,"height":169,"mime-type":"image\/jpeg","filesize":6340,"url":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/07\/d-110-bambu-residencial-puerto-valalrta-1-300x169.jpg"},"large":{"file":"d-110-bambu-residencial-puerto-valalrta-1-1024x576.jpg","width":1024,"height":576,"mime-type":"image\/jpeg","filesize":39460,"url":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/07\/d-110-bambu-residencial-puerto-valalrta-1-1024x576.jpg"},"thumbnail":{"file":"d-110-bambu-residencial-puerto-valalrta-1-150x150.jpg","width":150,"height":150,"mime-type":"image\/jpeg","filesize":5070,"url":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/07\/d-110-bambu-residencial-puerto-valalrta-1-150x150.jpg"},"medium_large":{"file":"d-110-bambu-residencial-puerto-valalrta-1-768x432.jpg","width":768,"height":432,"mime-type":"image\/jpeg","filesize":26265,"url":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/07\/d-110-bambu-residencial-puerto-valalrta-1-768x432.jpg"},"post-thumbnail":{"file":"d-110-bambu-residencial-puerto-valalrta-1-150x84.jpg","width":150,"height":84,"mime-type":"image\/jpeg","filesize":2576,"url":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/07\/d-110-bambu-residencial-puerto-valalrta-1-150x84.jpg"},"modern-property-child-slider":{"file":"d-110-bambu-residencial-puerto-valalrta-1-680x510.jpg","width":680,"height":510,"mime-type":"image\/jpeg","filesize":32273,"url":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/07\/d-110-bambu-residencial-puerto-valalrta-1-680x510.jpg"},"property-thumb-image":{"file":"d-110-bambu-residencial-puerto-valalrta-1-488x326.jpg","width":488,"height":326,"mime-type":"image\/jpeg","filesize":16415,"url":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/07\/d-110-bambu-residencial-puerto-valalrta-1-488x326.jpg"},"property-detail-video-image":{"file":"d-110-bambu-residencial-puerto-valalrta-1-818x417.jpg","width":818,"height":417,"mime-type":"image\/jpeg","filesize":27478,"url":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/07\/d-110-bambu-residencial-puerto-valalrta-1-818x417.jpg"},"agent-image":{"file":"d-110-bambu-residencial-puerto-valalrta-1-210x210.jpg","width":210,"height":210,"mime-type":"image\/jpeg","filesize":8078,"url":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/07\/d-110-bambu-residencial-puerto-valalrta-1-210x210.jpg"},"partners-logo":{"file":"d-110-bambu-residencial-puerto-valalrta-1-600x720.jpg","width":600,"height":720,"mime-type":"image\/jpeg","filesize":54110,"url":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/07\/d-110-bambu-residencial-puerto-valalrta-1-600x720.jpg"},"post-featured-image":{"file":"d-110-bambu-residencial-puerto-valalrta-1-1240x720.jpg","width":1240,"height":720,"mime-type":"image\/jpeg","filesize":61310,"url":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/07\/d-110-bambu-residencial-puerto-valalrta-1-1240x720.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]},"ID":"9518","name":"d-110-bambu-residencial-puerto-valalrta-1.jpg","path":"\/home\/casaqpta\/casaopcion.com\/en\/wp-content\/uploads\/2024\/07\/d-110-bambu-residencial-puerto-valalrta-1.jpg","url":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/07\/d-110-bambu-residencial-puerto-valalrta-1-150x150.jpg","full_url":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/07\/d-110-bambu-residencial-puerto-valalrta-1.jpg","title":"d-110-bambu-residencial-puerto-valalrta-1","caption":"","description":"","alt":"","srcset":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/07\/d-110-bambu-residencial-puerto-valalrta-1-150x150.jpg 150w, https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/07\/d-110-bambu-residencial-puerto-valalrta-1-210x210.jpg 210w"},{"width":150,"height":150,"file":"2024\/07\/d-110-bambu-residencial-puerto-valalrta-6.jpg","filesize":196875,"sizes":{"medium":{"file":"d-110-bambu-residencial-puerto-valalrta-6-300x169.jpg","width":300,"height":169,"mime-type":"image\/jpeg","filesize":5426,"url":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/07\/d-110-bambu-residencial-puerto-valalrta-6-300x169.jpg"},"large":{"file":"d-110-bambu-residencial-puerto-valalrta-6-1024x576.jpg","width":1024,"height":576,"mime-type":"image\/jpeg","filesize":35424,"url":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/07\/d-110-bambu-residencial-puerto-valalrta-6-1024x576.jpg"},"thumbnail":{"file":"d-110-bambu-residencial-puerto-valalrta-6-150x150.jpg","width":150,"height":150,"mime-type":"image\/jpeg","filesize":4217,"url":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/07\/d-110-bambu-residencial-puerto-valalrta-6-150x150.jpg"},"medium_large":{"file":"d-110-bambu-residencial-puerto-valalrta-6-768x432.jpg","width":768,"height":432,"mime-type":"image\/jpeg","filesize":21261,"url":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/07\/d-110-bambu-residencial-puerto-valalrta-6-768x432.jpg"},"post-thumbnail":{"file":"d-110-bambu-residencial-puerto-valalrta-6-150x84.jpg","width":150,"height":84,"mime-type":"image\/jpeg","filesize":2295,"url":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/07\/d-110-bambu-residencial-puerto-valalrta-6-150x84.jpg"},"modern-property-child-slider":{"file":"d-110-bambu-residencial-puerto-valalrta-6-680x510.jpg","width":680,"height":510,"mime-type":"image\/jpeg","filesize":27391,"url":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/07\/d-110-bambu-residencial-puerto-valalrta-6-680x510.jpg"},"property-thumb-image":{"file":"d-110-bambu-residencial-puerto-valalrta-6-488x326.jpg","width":488,"height":326,"mime-type":"image\/jpeg","filesize":13896,"url":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/07\/d-110-bambu-residencial-puerto-valalrta-6-488x326.jpg"},"property-detail-video-image":{"file":"d-110-bambu-residencial-puerto-valalrta-6-818x417.jpg","width":818,"height":417,"mime-type":"image\/jpeg","filesize":23195,"url":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/07\/d-110-bambu-residencial-puerto-valalrta-6-818x417.jpg"},"agent-image":{"file":"d-110-bambu-residencial-puerto-valalrta-6-210x210.jpg","width":210,"height":210,"mime-type":"image\/jpeg","filesize":6665,"url":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/07\/d-110-bambu-residencial-puerto-valalrta-6-210x210.jpg"},"partners-logo":{"file":"d-110-bambu-residencial-puerto-valalrta-6-600x720.jpg","width":600,"height":720,"mime-type":"image\/jpeg","filesize":47891,"url":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/07\/d-110-bambu-residencial-puerto-valalrta-6-600x720.jpg"},"post-featured-image":{"file":"d-110-bambu-residencial-puerto-valalrta-6-1240x720.jpg","width":1240,"height":720,"mime-type":"image\/jpeg","filesize":55183,"url":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/07\/d-110-bambu-residencial-puerto-valalrta-6-1240x720.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]},"ID":"9523","name":"d-110-bambu-residencial-puerto-valalrta-6.jpg","path":"\/home\/casaqpta\/casaopcion.com\/en\/wp-content\/uploads\/2024\/07\/d-110-bambu-residencial-puerto-valalrta-6.jpg","url":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/07\/d-110-bambu-residencial-puerto-valalrta-6-150x150.jpg","full_url":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/07\/d-110-bambu-residencial-puerto-valalrta-6.jpg","title":"d-110-bambu-residencial-puerto-valalrta-6","caption":"","description":"","alt":"","srcset":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/07\/d-110-bambu-residencial-puerto-valalrta-6-150x150.jpg 150w, https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/07\/d-110-bambu-residencial-puerto-valalrta-6-210x210.jpg 210w"},{"width":150,"height":150,"file":"2024\/07\/d-110-bambu-residencial-puerto-valalrta-5.jpg","filesize":272899,"sizes":{"medium":{"file":"d-110-bambu-residencial-puerto-valalrta-5-300x169.jpg","width":300,"height":169,"mime-type":"image\/jpeg","filesize":6439,"url":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/07\/d-110-bambu-residencial-puerto-valalrta-5-300x169.jpg"},"large":{"file":"d-110-bambu-residencial-puerto-valalrta-5-1024x576.jpg","width":1024,"height":576,"mime-type":"image\/jpeg","filesize":45984,"url":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/07\/d-110-bambu-residencial-puerto-valalrta-5-1024x576.jpg"},"thumbnail":{"file":"d-110-bambu-residencial-puerto-valalrta-5-150x150.jpg","width":150,"height":150,"mime-type":"image\/jpeg","filesize":5133,"url":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/07\/d-110-bambu-residencial-puerto-valalrta-5-150x150.jpg"},"medium_large":{"file":"d-110-bambu-residencial-puerto-valalrta-5-768x432.jpg","width":768,"height":432,"mime-type":"image\/jpeg","filesize":27769,"url":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/07\/d-110-bambu-residencial-puerto-valalrta-5-768x432.jpg"},"post-thumbnail":{"file":"d-110-bambu-residencial-puerto-valalrta-5-150x84.jpg","width":150,"height":84,"mime-type":"image\/jpeg","filesize":2566,"url":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/07\/d-110-bambu-residencial-puerto-valalrta-5-150x84.jpg"},"modern-property-child-slider":{"file":"d-110-bambu-residencial-puerto-valalrta-5-680x510.jpg","width":680,"height":510,"mime-type":"image\/jpeg","filesize":35816,"url":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/07\/d-110-bambu-residencial-puerto-valalrta-5-680x510.jpg"},"property-thumb-image":{"file":"d-110-bambu-residencial-puerto-valalrta-5-488x326.jpg","width":488,"height":326,"mime-type":"image\/jpeg","filesize":17717,"url":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/07\/d-110-bambu-residencial-puerto-valalrta-5-488x326.jpg"},"property-detail-video-image":{"file":"d-110-bambu-residencial-puerto-valalrta-5-818x417.jpg","width":818,"height":417,"mime-type":"image\/jpeg","filesize":30041,"url":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/07\/d-110-bambu-residencial-puerto-valalrta-5-818x417.jpg"},"agent-image":{"file":"d-110-bambu-residencial-puerto-valalrta-5-210x210.jpg","width":210,"height":210,"mime-type":"image\/jpeg","filesize":8401,"url":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/07\/d-110-bambu-residencial-puerto-valalrta-5-210x210.jpg"},"partners-logo":{"file":"d-110-bambu-residencial-puerto-valalrta-5-600x720.jpg","width":600,"height":720,"mime-type":"image\/jpeg","filesize":65307,"url":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/07\/d-110-bambu-residencial-puerto-valalrta-5-600x720.jpg"},"post-featured-image":{"file":"d-110-bambu-residencial-puerto-valalrta-5-1240x720.jpg","width":1240,"height":720,"mime-type":"image\/jpeg","filesize":72657,"url":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/07\/d-110-bambu-residencial-puerto-valalrta-5-1240x720.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]},"ID":"9522","name":"d-110-bambu-residencial-puerto-valalrta-5.jpg","path":"\/home\/casaqpta\/casaopcion.com\/en\/wp-content\/uploads\/2024\/07\/d-110-bambu-residencial-puerto-valalrta-5.jpg","url":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/07\/d-110-bambu-residencial-puerto-valalrta-5-150x150.jpg","full_url":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/07\/d-110-bambu-residencial-puerto-valalrta-5.jpg","title":"d-110-bambu-residencial-puerto-valalrta-5","caption":"","description":"","alt":"","srcset":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/07\/d-110-bambu-residencial-puerto-valalrta-5-150x150.jpg 150w, https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/07\/d-110-bambu-residencial-puerto-valalrta-5-210x210.jpg 210w"},{"width":150,"height":150,"file":"2024\/07\/d-110-bambu-residencial-puerto-valalrta-4.jpg","filesize":224280,"sizes":{"medium":{"file":"d-110-bambu-residencial-puerto-valalrta-4-300x169.jpg","width":300,"height":169,"mime-type":"image\/jpeg","filesize":6317,"url":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/07\/d-110-bambu-residencial-puerto-valalrta-4-300x169.jpg"},"large":{"file":"d-110-bambu-residencial-puerto-valalrta-4-1024x576.jpg","width":1024,"height":576,"mime-type":"image\/jpeg","filesize":39584,"url":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/07\/d-110-bambu-residencial-puerto-valalrta-4-1024x576.jpg"},"thumbnail":{"file":"d-110-bambu-residencial-puerto-valalrta-4-150x150.jpg","width":150,"height":150,"mime-type":"image\/jpeg","filesize":5139,"url":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/07\/d-110-bambu-residencial-puerto-valalrta-4-150x150.jpg"},"medium_large":{"file":"d-110-bambu-residencial-puerto-valalrta-4-768x432.jpg","width":768,"height":432,"mime-type":"image\/jpeg","filesize":25632,"url":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/07\/d-110-bambu-residencial-puerto-valalrta-4-768x432.jpg"},"post-thumbnail":{"file":"d-110-bambu-residencial-puerto-valalrta-4-150x84.jpg","width":150,"height":84,"mime-type":"image\/jpeg","filesize":2581,"url":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/07\/d-110-bambu-residencial-puerto-valalrta-4-150x84.jpg"},"modern-property-child-slider":{"file":"d-110-bambu-residencial-puerto-valalrta-4-680x510.jpg","width":680,"height":510,"mime-type":"image\/jpeg","filesize":31249,"url":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/07\/d-110-bambu-residencial-puerto-valalrta-4-680x510.jpg"},"property-thumb-image":{"file":"d-110-bambu-residencial-puerto-valalrta-4-488x326.jpg","width":488,"height":326,"mime-type":"image\/jpeg","filesize":15997,"url":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/07\/d-110-bambu-residencial-puerto-valalrta-4-488x326.jpg"},"property-detail-video-image":{"file":"d-110-bambu-residencial-puerto-valalrta-4-818x417.jpg","width":818,"height":417,"mime-type":"image\/jpeg","filesize":26339,"url":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/07\/d-110-bambu-residencial-puerto-valalrta-4-818x417.jpg"},"agent-image":{"file":"d-110-bambu-residencial-puerto-valalrta-4-210x210.jpg","width":210,"height":210,"mime-type":"image\/jpeg","filesize":8177,"url":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/07\/d-110-bambu-residencial-puerto-valalrta-4-210x210.jpg"},"partners-logo":{"file":"d-110-bambu-residencial-puerto-valalrta-4-600x720.jpg","width":600,"height":720,"mime-type":"image\/jpeg","filesize":52366,"url":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/07\/d-110-bambu-residencial-puerto-valalrta-4-600x720.jpg"},"post-featured-image":{"file":"d-110-bambu-residencial-puerto-valalrta-4-1240x720.jpg","width":1240,"height":720,"mime-type":"image\/jpeg","filesize":59692,"url":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/07\/d-110-bambu-residencial-puerto-valalrta-4-1240x720.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]},"ID":"9521","name":"d-110-bambu-residencial-puerto-valalrta-4.jpg","path":"\/home\/casaqpta\/casaopcion.com\/en\/wp-content\/uploads\/2024\/07\/d-110-bambu-residencial-puerto-valalrta-4.jpg","url":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/07\/d-110-bambu-residencial-puerto-valalrta-4-150x150.jpg","full_url":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/07\/d-110-bambu-residencial-puerto-valalrta-4.jpg","title":"d-110-bambu-residencial-puerto-valalrta-4","caption":"","description":"","alt":"","srcset":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/07\/d-110-bambu-residencial-puerto-valalrta-4-150x150.jpg 150w, https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/07\/d-110-bambu-residencial-puerto-valalrta-4-210x210.jpg 210w"},{"width":150,"height":150,"file":"2024\/07\/d-110-bambu-residencial-puerto-valalrta-3.jpg","filesize":245177,"sizes":{"medium":{"file":"d-110-bambu-residencial-puerto-valalrta-3-300x169.jpg","width":300,"height":169,"mime-type":"image\/jpeg","filesize":6411,"url":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/07\/d-110-bambu-residencial-puerto-valalrta-3-300x169.jpg"},"large":{"file":"d-110-bambu-residencial-puerto-valalrta-3-1024x576.jpg","width":1024,"height":576,"mime-type":"image\/jpeg","filesize":41566,"url":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/07\/d-110-bambu-residencial-puerto-valalrta-3-1024x576.jpg"},"thumbnail":{"file":"d-110-bambu-residencial-puerto-valalrta-3-150x150.jpg","width":150,"height":150,"mime-type":"image\/jpeg","filesize":5168,"url":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/07\/d-110-bambu-residencial-puerto-valalrta-3-150x150.jpg"},"medium_large":{"file":"d-110-bambu-residencial-puerto-valalrta-3-768x432.jpg","width":768,"height":432,"mime-type":"image\/jpeg","filesize":26248,"url":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/07\/d-110-bambu-residencial-puerto-valalrta-3-768x432.jpg"},"post-thumbnail":{"file":"d-110-bambu-residencial-puerto-valalrta-3-150x84.jpg","width":150,"height":84,"mime-type":"image\/jpeg","filesize":2570,"url":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/07\/d-110-bambu-residencial-puerto-valalrta-3-150x84.jpg"},"modern-property-child-slider":{"file":"d-110-bambu-residencial-puerto-valalrta-3-680x510.jpg","width":680,"height":510,"mime-type":"image\/jpeg","filesize":32490,"url":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/07\/d-110-bambu-residencial-puerto-valalrta-3-680x510.jpg"},"property-thumb-image":{"file":"d-110-bambu-residencial-puerto-valalrta-3-488x326.jpg","width":488,"height":326,"mime-type":"image\/jpeg","filesize":16736,"url":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/07\/d-110-bambu-residencial-puerto-valalrta-3-488x326.jpg"},"property-detail-video-image":{"file":"d-110-bambu-residencial-puerto-valalrta-3-818x417.jpg","width":818,"height":417,"mime-type":"image\/jpeg","filesize":27683,"url":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/07\/d-110-bambu-residencial-puerto-valalrta-3-818x417.jpg"},"agent-image":{"file":"d-110-bambu-residencial-puerto-valalrta-3-210x210.jpg","width":210,"height":210,"mime-type":"image\/jpeg","filesize":8138,"url":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/07\/d-110-bambu-residencial-puerto-valalrta-3-210x210.jpg"},"partners-logo":{"file":"d-110-bambu-residencial-puerto-valalrta-3-600x720.jpg","width":600,"height":720,"mime-type":"image\/jpeg","filesize":55571,"url":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/07\/d-110-bambu-residencial-puerto-valalrta-3-600x720.jpg"},"post-featured-image":{"file":"d-110-bambu-residencial-puerto-valalrta-3-1240x720.jpg","width":1240,"height":720,"mime-type":"image\/jpeg","filesize":62899,"url":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/07\/d-110-bambu-residencial-puerto-valalrta-3-1240x720.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]},"ID":"9520","name":"d-110-bambu-residencial-puerto-valalrta-3.jpg","path":"\/home\/casaqpta\/casaopcion.com\/en\/wp-content\/uploads\/2024\/07\/d-110-bambu-residencial-puerto-valalrta-3.jpg","url":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/07\/d-110-bambu-residencial-puerto-valalrta-3-150x150.jpg","full_url":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/07\/d-110-bambu-residencial-puerto-valalrta-3.jpg","title":"d-110-bambu-residencial-puerto-valalrta-3","caption":"","description":"","alt":"","srcset":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/07\/d-110-bambu-residencial-puerto-valalrta-3-150x150.jpg 150w, https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/07\/d-110-bambu-residencial-puerto-valalrta-3-210x210.jpg 210w"},{"width":150,"height":150,"file":"2024\/07\/d-110-bambu-residencial-puerto-valalrta-2.jpg","filesize":179014,"sizes":{"medium":{"file":"d-110-bambu-residencial-puerto-valalrta-2-300x169.jpg","width":300,"height":169,"mime-type":"image\/jpeg","filesize":5475,"url":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/07\/d-110-bambu-residencial-puerto-valalrta-2-300x169.jpg"},"large":{"file":"d-110-bambu-residencial-puerto-valalrta-2-1024x576.jpg","width":1024,"height":576,"mime-type":"image\/jpeg","filesize":32750,"url":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/07\/d-110-bambu-residencial-puerto-valalrta-2-1024x576.jpg"},"thumbnail":{"file":"d-110-bambu-residencial-puerto-valalrta-2-150x150.jpg","width":150,"height":150,"mime-type":"image\/jpeg","filesize":4405,"url":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/07\/d-110-bambu-residencial-puerto-valalrta-2-150x150.jpg"},"medium_large":{"file":"d-110-bambu-residencial-puerto-valalrta-2-768x432.jpg","width":768,"height":432,"mime-type":"image\/jpeg","filesize":20435,"url":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/07\/d-110-bambu-residencial-puerto-valalrta-2-768x432.jpg"},"post-thumbnail":{"file":"d-110-bambu-residencial-puerto-valalrta-2-150x84.jpg","width":150,"height":84,"mime-type":"image\/jpeg","filesize":2406,"url":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/07\/d-110-bambu-residencial-puerto-valalrta-2-150x84.jpg"},"modern-property-child-slider":{"file":"d-110-bambu-residencial-puerto-valalrta-2-680x510.jpg","width":680,"height":510,"mime-type":"image\/jpeg","filesize":25483,"url":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/07\/d-110-bambu-residencial-puerto-valalrta-2-680x510.jpg"},"property-thumb-image":{"file":"d-110-bambu-residencial-puerto-valalrta-2-488x326.jpg","width":488,"height":326,"mime-type":"image\/jpeg","filesize":13560,"url":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/07\/d-110-bambu-residencial-puerto-valalrta-2-488x326.jpg"},"property-detail-video-image":{"file":"d-110-bambu-residencial-puerto-valalrta-2-818x417.jpg","width":818,"height":417,"mime-type":"image\/jpeg","filesize":22110,"url":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/07\/d-110-bambu-residencial-puerto-valalrta-2-818x417.jpg"},"agent-image":{"file":"d-110-bambu-residencial-puerto-valalrta-2-210x210.jpg","width":210,"height":210,"mime-type":"image\/jpeg","filesize":6891,"url":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/07\/d-110-bambu-residencial-puerto-valalrta-2-210x210.jpg"},"partners-logo":{"file":"d-110-bambu-residencial-puerto-valalrta-2-600x720.jpg","width":600,"height":720,"mime-type":"image\/jpeg","filesize":41402,"url":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/07\/d-110-bambu-residencial-puerto-valalrta-2-600x720.jpg"},"post-featured-image":{"file":"d-110-bambu-residencial-puerto-valalrta-2-1240x720.jpg","width":1240,"height":720,"mime-type":"image\/jpeg","filesize":48737,"url":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/07\/d-110-bambu-residencial-puerto-valalrta-2-1240x720.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]},"ID":"9519","name":"d-110-bambu-residencial-puerto-valalrta-2.jpg","path":"\/home\/casaqpta\/casaopcion.com\/en\/wp-content\/uploads\/2024\/07\/d-110-bambu-residencial-puerto-valalrta-2.jpg","url":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/07\/d-110-bambu-residencial-puerto-valalrta-2-150x150.jpg","full_url":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/07\/d-110-bambu-residencial-puerto-valalrta-2.jpg","title":"d-110-bambu-residencial-puerto-valalrta-2","caption":"","description":"","alt":"","srcset":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/07\/d-110-bambu-residencial-puerto-valalrta-2-150x150.jpg 150w, https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/07\/d-110-bambu-residencial-puerto-valalrta-2-210x210.jpg 210w"},{"width":150,"height":150,"file":"2024\/07\/d-110-bambu-residencial-puerto-valalrta-8.jpg","filesize":179924,"sizes":{"medium":{"file":"d-110-bambu-residencial-puerto-valalrta-8-300x169.jpg","width":300,"height":169,"mime-type":"image\/jpeg","filesize":4973,"url":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/07\/d-110-bambu-residencial-puerto-valalrta-8-300x169.jpg"},"large":{"file":"d-110-bambu-residencial-puerto-valalrta-8-1024x576.jpg","width":1024,"height":576,"mime-type":"image\/jpeg","filesize":32263,"url":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/07\/d-110-bambu-residencial-puerto-valalrta-8-1024x576.jpg"},"thumbnail":{"file":"d-110-bambu-residencial-puerto-valalrta-8-150x150.jpg","width":150,"height":150,"mime-type":"image\/jpeg","filesize":3930,"url":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/07\/d-110-bambu-residencial-puerto-valalrta-8-150x150.jpg"},"medium_large":{"file":"d-110-bambu-residencial-puerto-valalrta-8-768x432.jpg","width":768,"height":432,"mime-type":"image\/jpeg","filesize":19513,"url":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/07\/d-110-bambu-residencial-puerto-valalrta-8-768x432.jpg"},"post-thumbnail":{"file":"d-110-bambu-residencial-puerto-valalrta-8-150x84.jpg","width":150,"height":84,"mime-type":"image\/jpeg","filesize":2231,"url":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/07\/d-110-bambu-residencial-puerto-valalrta-8-150x84.jpg"},"modern-property-child-slider":{"file":"d-110-bambu-residencial-puerto-valalrta-8-680x510.jpg","width":680,"height":510,"mime-type":"image\/jpeg","filesize":24743,"url":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/07\/d-110-bambu-residencial-puerto-valalrta-8-680x510.jpg"},"property-thumb-image":{"file":"d-110-bambu-residencial-puerto-valalrta-8-488x326.jpg","width":488,"height":326,"mime-type":"image\/jpeg","filesize":12597,"url":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/07\/d-110-bambu-residencial-puerto-valalrta-8-488x326.jpg"},"property-detail-video-image":{"file":"d-110-bambu-residencial-puerto-valalrta-8-818x417.jpg","width":818,"height":417,"mime-type":"image\/jpeg","filesize":20899,"url":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/07\/d-110-bambu-residencial-puerto-valalrta-8-818x417.jpg"},"agent-image":{"file":"d-110-bambu-residencial-puerto-valalrta-8-210x210.jpg","width":210,"height":210,"mime-type":"image\/jpeg","filesize":6277,"url":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/07\/d-110-bambu-residencial-puerto-valalrta-8-210x210.jpg"},"partners-logo":{"file":"d-110-bambu-residencial-puerto-valalrta-8-600x720.jpg","width":600,"height":720,"mime-type":"image\/jpeg","filesize":42546,"url":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/07\/d-110-bambu-residencial-puerto-valalrta-8-600x720.jpg"},"post-featured-image":{"file":"d-110-bambu-residencial-puerto-valalrta-8-1240x720.jpg","width":1240,"height":720,"mime-type":"image\/jpeg","filesize":49815,"url":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/07\/d-110-bambu-residencial-puerto-valalrta-8-1240x720.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]},"ID":"9511","name":"d-110-bambu-residencial-puerto-valalrta-8.jpg","path":"\/home\/casaqpta\/casaopcion.com\/en\/wp-content\/uploads\/2024\/07\/d-110-bambu-residencial-puerto-valalrta-8.jpg","url":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/07\/d-110-bambu-residencial-puerto-valalrta-8-150x150.jpg","full_url":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/07\/d-110-bambu-residencial-puerto-valalrta-8.jpg","title":"d-110-bambu-residencial-puerto-valalrta-8","caption":"","description":"","alt":"","srcset":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/07\/d-110-bambu-residencial-puerto-valalrta-8-150x150.jpg 150w, https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/07\/d-110-bambu-residencial-puerto-valalrta-8-210x210.jpg 210w"},{"width":150,"height":150,"file":"2024\/07\/d-110-bambu-residencial-puerto-valalrta-9.jpg","filesize":247410,"sizes":{"medium":{"file":"d-110-bambu-residencial-puerto-valalrta-9-300x169.jpg","width":300,"height":169,"mime-type":"image\/jpeg","filesize":6163,"url":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/07\/d-110-bambu-residencial-puerto-valalrta-9-300x169.jpg"},"large":{"file":"d-110-bambu-residencial-puerto-valalrta-9-1024x576.jpg","width":1024,"height":576,"mime-type":"image\/jpeg","filesize":44670,"url":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/07\/d-110-bambu-residencial-puerto-valalrta-9-1024x576.jpg"},"thumbnail":{"file":"d-110-bambu-residencial-puerto-valalrta-9-150x150.jpg","width":150,"height":150,"mime-type":"image\/jpeg","filesize":5022,"url":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/07\/d-110-bambu-residencial-puerto-valalrta-9-150x150.jpg"},"medium_large":{"file":"d-110-bambu-residencial-puerto-valalrta-9-768x432.jpg","width":768,"height":432,"mime-type":"image\/jpeg","filesize":28081,"url":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/07\/d-110-bambu-residencial-puerto-valalrta-9-768x432.jpg"},"post-thumbnail":{"file":"d-110-bambu-residencial-puerto-valalrta-9-150x84.jpg","width":150,"height":84,"mime-type":"image\/jpeg","filesize":2449,"url":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/07\/d-110-bambu-residencial-puerto-valalrta-9-150x84.jpg"},"modern-property-child-slider":{"file":"d-110-bambu-residencial-puerto-valalrta-9-680x510.jpg","width":680,"height":510,"mime-type":"image\/jpeg","filesize":34942,"url":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/07\/d-110-bambu-residencial-puerto-valalrta-9-680x510.jpg"},"property-thumb-image":{"file":"d-110-bambu-residencial-puerto-valalrta-9-488x326.jpg","width":488,"height":326,"mime-type":"image\/jpeg","filesize":17001,"url":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/07\/d-110-bambu-residencial-puerto-valalrta-9-488x326.jpg"},"property-detail-video-image":{"file":"d-110-bambu-residencial-puerto-valalrta-9-818x417.jpg","width":818,"height":417,"mime-type":"image\/jpeg","filesize":29680,"url":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/07\/d-110-bambu-residencial-puerto-valalrta-9-818x417.jpg"},"agent-image":{"file":"d-110-bambu-residencial-puerto-valalrta-9-210x210.jpg","width":210,"height":210,"mime-type":"image\/jpeg","filesize":8008,"url":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/07\/d-110-bambu-residencial-puerto-valalrta-9-210x210.jpg"},"partners-logo":{"file":"d-110-bambu-residencial-puerto-valalrta-9-600x720.jpg","width":600,"height":720,"mime-type":"image\/jpeg","filesize":62501,"url":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/07\/d-110-bambu-residencial-puerto-valalrta-9-600x720.jpg"},"post-featured-image":{"file":"d-110-bambu-residencial-puerto-valalrta-9-1240x720.jpg","width":1240,"height":720,"mime-type":"image\/jpeg","filesize":69880,"url":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/07\/d-110-bambu-residencial-puerto-valalrta-9-1240x720.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]},"ID":"9512","name":"d-110-bambu-residencial-puerto-valalrta-9.jpg","path":"\/home\/casaqpta\/casaopcion.com\/en\/wp-content\/uploads\/2024\/07\/d-110-bambu-residencial-puerto-valalrta-9.jpg","url":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/07\/d-110-bambu-residencial-puerto-valalrta-9-150x150.jpg","full_url":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/07\/d-110-bambu-residencial-puerto-valalrta-9.jpg","title":"d-110-bambu-residencial-puerto-valalrta-9","caption":"","description":"","alt":"","srcset":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/07\/d-110-bambu-residencial-puerto-valalrta-9-150x150.jpg 150w, https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/07\/d-110-bambu-residencial-puerto-valalrta-9-210x210.jpg 210w"},{"width":150,"height":150,"file":"2024\/07\/d-110-bambu-residencial-puerto-valalrta-10.jpg","filesize":173455,"sizes":{"medium":{"file":"d-110-bambu-residencial-puerto-valalrta-10-300x169.jpg","width":300,"height":169,"mime-type":"image\/jpeg","filesize":5033,"url":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/07\/d-110-bambu-residencial-puerto-valalrta-10-300x169.jpg"},"large":{"file":"d-110-bambu-residencial-puerto-valalrta-10-1024x576.jpg","width":1024,"height":576,"mime-type":"image\/jpeg","filesize":30794,"url":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/07\/d-110-bambu-residencial-puerto-valalrta-10-1024x576.jpg"},"thumbnail":{"file":"d-110-bambu-residencial-puerto-valalrta-10-150x150.jpg","width":150,"height":150,"mime-type":"image\/jpeg","filesize":3982,"url":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/07\/d-110-bambu-residencial-puerto-valalrta-10-150x150.jpg"},"medium_large":{"file":"d-110-bambu-residencial-puerto-valalrta-10-768x432.jpg","width":768,"height":432,"mime-type":"image\/jpeg","filesize":19518,"url":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/07\/d-110-bambu-residencial-puerto-valalrta-10-768x432.jpg"},"post-thumbnail":{"file":"d-110-bambu-residencial-puerto-valalrta-10-150x84.jpg","width":150,"height":84,"mime-type":"image\/jpeg","filesize":2252,"url":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/07\/d-110-bambu-residencial-puerto-valalrta-10-150x84.jpg"},"modern-property-child-slider":{"file":"d-110-bambu-residencial-puerto-valalrta-10-680x510.jpg","width":680,"height":510,"mime-type":"image\/jpeg","filesize":23833,"url":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/07\/d-110-bambu-residencial-puerto-valalrta-10-680x510.jpg"},"property-thumb-image":{"file":"d-110-bambu-residencial-puerto-valalrta-10-488x326.jpg","width":488,"height":326,"mime-type":"image\/jpeg","filesize":12163,"url":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/07\/d-110-bambu-residencial-puerto-valalrta-10-488x326.jpg"},"property-detail-video-image":{"file":"d-110-bambu-residencial-puerto-valalrta-10-818x417.jpg","width":818,"height":417,"mime-type":"image\/jpeg","filesize":20561,"url":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/07\/d-110-bambu-residencial-puerto-valalrta-10-818x417.jpg"},"agent-image":{"file":"d-110-bambu-residencial-puerto-valalrta-10-210x210.jpg","width":210,"height":210,"mime-type":"image\/jpeg","filesize":6260,"url":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/07\/d-110-bambu-residencial-puerto-valalrta-10-210x210.jpg"},"partners-logo":{"file":"d-110-bambu-residencial-puerto-valalrta-10-600x720.jpg","width":600,"height":720,"mime-type":"image\/jpeg","filesize":37452,"url":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/07\/d-110-bambu-residencial-puerto-valalrta-10-600x720.jpg"},"post-featured-image":{"file":"d-110-bambu-residencial-puerto-valalrta-10-1240x720.jpg","width":1240,"height":720,"mime-type":"image\/jpeg","filesize":44652,"url":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/07\/d-110-bambu-residencial-puerto-valalrta-10-1240x720.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]},"ID":"9513","name":"d-110-bambu-residencial-puerto-valalrta-10.jpg","path":"\/home\/casaqpta\/casaopcion.com\/en\/wp-content\/uploads\/2024\/07\/d-110-bambu-residencial-puerto-valalrta-10.jpg","url":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/07\/d-110-bambu-residencial-puerto-valalrta-10-150x150.jpg","full_url":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/07\/d-110-bambu-residencial-puerto-valalrta-10.jpg","title":"d-110-bambu-residencial-puerto-valalrta-10","caption":"","description":"","alt":"","srcset":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/07\/d-110-bambu-residencial-puerto-valalrta-10-150x150.jpg 150w, https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/07\/d-110-bambu-residencial-puerto-valalrta-10-210x210.jpg 210w"},{"width":150,"height":150,"file":"2024\/07\/d-110-bambu-residencial-puerto-valalrta-7.jpg","filesize":233912,"sizes":{"medium":{"file":"d-110-bambu-residencial-puerto-valalrta-7-300x169.jpg","width":300,"height":169,"mime-type":"image\/jpeg","filesize":6185,"url":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/07\/d-110-bambu-residencial-puerto-valalrta-7-300x169.jpg"},"large":{"file":"d-110-bambu-residencial-puerto-valalrta-7-1024x576.jpg","width":1024,"height":576,"mime-type":"image\/jpeg","filesize":41397,"url":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/07\/d-110-bambu-residencial-puerto-valalrta-7-1024x576.jpg"},"thumbnail":{"file":"d-110-bambu-residencial-puerto-valalrta-7-150x150.jpg","width":150,"height":150,"mime-type":"image\/jpeg","filesize":4997,"url":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/07\/d-110-bambu-residencial-puerto-valalrta-7-150x150.jpg"},"medium_large":{"file":"d-110-bambu-residencial-puerto-valalrta-7-768x432.jpg","width":768,"height":432,"mime-type":"image\/jpeg","filesize":25507,"url":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/07\/d-110-bambu-residencial-puerto-valalrta-7-768x432.jpg"},"post-thumbnail":{"file":"d-110-bambu-residencial-puerto-valalrta-7-150x84.jpg","width":150,"height":84,"mime-type":"image\/jpeg","filesize":2498,"url":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/07\/d-110-bambu-residencial-puerto-valalrta-7-150x84.jpg"},"modern-property-child-slider":{"file":"d-110-bambu-residencial-puerto-valalrta-7-680x510.jpg","width":680,"height":510,"mime-type":"image\/jpeg","filesize":32164,"url":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/07\/d-110-bambu-residencial-puerto-valalrta-7-680x510.jpg"},"property-thumb-image":{"file":"d-110-bambu-residencial-puerto-valalrta-7-488x326.jpg","width":488,"height":326,"mime-type":"image\/jpeg","filesize":16366,"url":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/07\/d-110-bambu-residencial-puerto-valalrta-7-488x326.jpg"},"property-detail-video-image":{"file":"d-110-bambu-residencial-puerto-valalrta-7-818x417.jpg","width":818,"height":417,"mime-type":"image\/jpeg","filesize":26659,"url":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/07\/d-110-bambu-residencial-puerto-valalrta-7-818x417.jpg"},"agent-image":{"file":"d-110-bambu-residencial-puerto-valalrta-7-210x210.jpg","width":210,"height":210,"mime-type":"image\/jpeg","filesize":8055,"url":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/07\/d-110-bambu-residencial-puerto-valalrta-7-210x210.jpg"},"partners-logo":{"file":"d-110-bambu-residencial-puerto-valalrta-7-600x720.jpg","width":600,"height":720,"mime-type":"image\/jpeg","filesize":56609,"url":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/07\/d-110-bambu-residencial-puerto-valalrta-7-600x720.jpg"},"post-featured-image":{"file":"d-110-bambu-residencial-puerto-valalrta-7-1240x720.jpg","width":1240,"height":720,"mime-type":"image\/jpeg","filesize":63970,"url":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/07\/d-110-bambu-residencial-puerto-valalrta-7-1240x720.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]},"ID":"9510","name":"d-110-bambu-residencial-puerto-valalrta-7.jpg","path":"\/home\/casaqpta\/casaopcion.com\/en\/wp-content\/uploads\/2024\/07\/d-110-bambu-residencial-puerto-valalrta-7.jpg","url":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/07\/d-110-bambu-residencial-puerto-valalrta-7-150x150.jpg","full_url":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/07\/d-110-bambu-residencial-puerto-valalrta-7.jpg","title":"d-110-bambu-residencial-puerto-valalrta-7","caption":"","description":"","alt":"","srcset":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/07\/d-110-bambu-residencial-puerto-valalrta-7-150x150.jpg 150w, https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/07\/d-110-bambu-residencial-puerto-valalrta-7-210x210.jpg 210w"},{"width":150,"height":150,"file":"2024\/07\/d-110-bambu-residencial-puerto-valalrta-12.jpg","filesize":318953,"sizes":{"medium":{"file":"d-110-bambu-residencial-puerto-valalrta-12-300x169.jpg","width":300,"height":169,"mime-type":"image\/jpeg","filesize":8995,"url":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/07\/d-110-bambu-residencial-puerto-valalrta-12-300x169.jpg"},"large":{"file":"d-110-bambu-residencial-puerto-valalrta-12-1024x576.jpg","width":1024,"height":576,"mime-type":"image\/jpeg","filesize":55531,"url":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/07\/d-110-bambu-residencial-puerto-valalrta-12-1024x576.jpg"},"thumbnail":{"file":"d-110-bambu-residencial-puerto-valalrta-12-150x150.jpg","width":150,"height":150,"mime-type":"image\/jpeg","filesize":4310,"url":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/07\/d-110-bambu-residencial-puerto-valalrta-12-150x150.jpg"},"medium_large":{"file":"d-110-bambu-residencial-puerto-valalrta-12-768x432.jpg","width":768,"height":432,"mime-type":"image\/jpeg","filesize":36153,"url":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/07\/d-110-bambu-residencial-puerto-valalrta-12-768x432.jpg"},"post-thumbnail":{"file":"d-110-bambu-residencial-puerto-valalrta-12-150x84.jpg","width":150,"height":84,"mime-type":"image\/jpeg","filesize":3409,"url":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/07\/d-110-bambu-residencial-puerto-valalrta-12-150x84.jpg"},"modern-property-child-slider":{"file":"d-110-bambu-residencial-puerto-valalrta-12-680x510.jpg","width":680,"height":510,"mime-type":"image\/jpeg","filesize":33900,"url":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/07\/d-110-bambu-residencial-puerto-valalrta-12-680x510.jpg"},"property-thumb-image":{"file":"d-110-bambu-residencial-puerto-valalrta-12-488x326.jpg","width":488,"height":326,"mime-type":"image\/jpeg","filesize":19563,"url":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/07\/d-110-bambu-residencial-puerto-valalrta-12-488x326.jpg"},"property-detail-video-image":{"file":"d-110-bambu-residencial-puerto-valalrta-12-818x417.jpg","width":818,"height":417,"mime-type":"image\/jpeg","filesize":38191,"url":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/07\/d-110-bambu-residencial-puerto-valalrta-12-818x417.jpg"},"agent-image":{"file":"d-110-bambu-residencial-puerto-valalrta-12-210x210.jpg","width":210,"height":210,"mime-type":"image\/jpeg","filesize":6901,"url":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/07\/d-110-bambu-residencial-puerto-valalrta-12-210x210.jpg"},"partners-logo":{"file":"d-110-bambu-residencial-puerto-valalrta-12-600x720.jpg","width":600,"height":720,"mime-type":"image\/jpeg","filesize":36218,"url":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/07\/d-110-bambu-residencial-puerto-valalrta-12-600x720.jpg"},"post-featured-image":{"file":"d-110-bambu-residencial-puerto-valalrta-12-1240x720.jpg","width":1240,"height":720,"mime-type":"image\/jpeg","filesize":79232,"url":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/07\/d-110-bambu-residencial-puerto-valalrta-12-1240x720.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]},"ID":"9515","name":"d-110-bambu-residencial-puerto-valalrta-12.jpg","path":"\/home\/casaqpta\/casaopcion.com\/en\/wp-content\/uploads\/2024\/07\/d-110-bambu-residencial-puerto-valalrta-12.jpg","url":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/07\/d-110-bambu-residencial-puerto-valalrta-12-150x150.jpg","full_url":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/07\/d-110-bambu-residencial-puerto-valalrta-12.jpg","title":"d-110-bambu-residencial-puerto-valalrta-12","caption":"","description":"","alt":"","srcset":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/07\/d-110-bambu-residencial-puerto-valalrta-12-150x150.jpg 150w, https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/07\/d-110-bambu-residencial-puerto-valalrta-12-210x210.jpg 210w"},{"width":150,"height":150,"file":"2024\/07\/d-110-bambu-residencial-puerto-valalrta-11.jpg","filesize":365202,"sizes":{"medium":{"file":"d-110-bambu-residencial-puerto-valalrta-11-300x169.jpg","width":300,"height":169,"mime-type":"image\/jpeg","filesize":10845,"url":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/07\/d-110-bambu-residencial-puerto-valalrta-11-300x169.jpg"},"large":{"file":"d-110-bambu-residencial-puerto-valalrta-11-1024x576.jpg","width":1024,"height":576,"mime-type":"image\/jpeg","filesize":65433,"url":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/07\/d-110-bambu-residencial-puerto-valalrta-11-1024x576.jpg"},"thumbnail":{"file":"d-110-bambu-residencial-puerto-valalrta-11-150x150.jpg","width":150,"height":150,"mime-type":"image\/jpeg","filesize":5668,"url":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/07\/d-110-bambu-residencial-puerto-valalrta-11-150x150.jpg"},"medium_large":{"file":"d-110-bambu-residencial-puerto-valalrta-11-768x432.jpg","width":768,"height":432,"mime-type":"image\/jpeg","filesize":43412,"url":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/07\/d-110-bambu-residencial-puerto-valalrta-11-768x432.jpg"},"post-thumbnail":{"file":"d-110-bambu-residencial-puerto-valalrta-11-150x84.jpg","width":150,"height":84,"mime-type":"image\/jpeg","filesize":4100,"url":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/07\/d-110-bambu-residencial-puerto-valalrta-11-150x84.jpg"},"modern-property-child-slider":{"file":"d-110-bambu-residencial-puerto-valalrta-11-680x510.jpg","width":680,"height":510,"mime-type":"image\/jpeg","filesize":44294,"url":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/07\/d-110-bambu-residencial-puerto-valalrta-11-680x510.jpg"},"property-thumb-image":{"file":"d-110-bambu-residencial-puerto-valalrta-11-488x326.jpg","width":488,"height":326,"mime-type":"image\/jpeg","filesize":25291,"url":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/07\/d-110-bambu-residencial-puerto-valalrta-11-488x326.jpg"},"property-detail-video-image":{"file":"d-110-bambu-residencial-puerto-valalrta-11-818x417.jpg","width":818,"height":417,"mime-type":"image\/jpeg","filesize":45051,"url":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/07\/d-110-bambu-residencial-puerto-valalrta-11-818x417.jpg"},"agent-image":{"file":"d-110-bambu-residencial-puerto-valalrta-11-210x210.jpg","width":210,"height":210,"mime-type":"image\/jpeg","filesize":9409,"url":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/07\/d-110-bambu-residencial-puerto-valalrta-11-210x210.jpg"},"partners-logo":{"file":"d-110-bambu-residencial-puerto-valalrta-11-600x720.jpg","width":600,"height":720,"mime-type":"image\/jpeg","filesize":45296,"url":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/07\/d-110-bambu-residencial-puerto-valalrta-11-600x720.jpg"},"post-featured-image":{"file":"d-110-bambu-residencial-puerto-valalrta-11-1240x720.jpg","width":1240,"height":720,"mime-type":"image\/jpeg","filesize":92607,"url":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/07\/d-110-bambu-residencial-puerto-valalrta-11-1240x720.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]},"ID":"9514","name":"d-110-bambu-residencial-puerto-valalrta-11.jpg","path":"\/home\/casaqpta\/casaopcion.com\/en\/wp-content\/uploads\/2024\/07\/d-110-bambu-residencial-puerto-valalrta-11.jpg","url":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/07\/d-110-bambu-residencial-puerto-valalrta-11-150x150.jpg","full_url":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/07\/d-110-bambu-residencial-puerto-valalrta-11.jpg","title":"d-110-bambu-residencial-puerto-valalrta-11","caption":"","description":"","alt":"","srcset":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/07\/d-110-bambu-residencial-puerto-valalrta-11-150x150.jpg 150w, https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/07\/d-110-bambu-residencial-puerto-valalrta-11-210x210.jpg 210w"},{"width":150,"height":150,"file":"2024\/07\/d-110-bambu-residencial-puerto-valalrta-13.jpg","filesize":398599,"sizes":{"medium":{"file":"d-110-bambu-residencial-puerto-valalrta-13-300x169.jpg","width":300,"height":169,"mime-type":"image\/jpeg","filesize":11367,"url":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/07\/d-110-bambu-residencial-puerto-valalrta-13-300x169.jpg"},"large":{"file":"d-110-bambu-residencial-puerto-valalrta-13-1024x576.jpg","width":1024,"height":576,"mime-type":"image\/jpeg","filesize":66381,"url":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/07\/d-110-bambu-residencial-puerto-valalrta-13-1024x576.jpg"},"thumbnail":{"file":"d-110-bambu-residencial-puerto-valalrta-13-150x150.jpg","width":150,"height":150,"mime-type":"image\/jpeg","filesize":5639,"url":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/07\/d-110-bambu-residencial-puerto-valalrta-13-150x150.jpg"},"medium_large":{"file":"d-110-bambu-residencial-puerto-valalrta-13-768x432.jpg","width":768,"height":432,"mime-type":"image\/jpeg","filesize":44276,"url":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/07\/d-110-bambu-residencial-puerto-valalrta-13-768x432.jpg"},"post-thumbnail":{"file":"d-110-bambu-residencial-puerto-valalrta-13-150x84.jpg","width":150,"height":84,"mime-type":"image\/jpeg","filesize":4192,"url":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/07\/d-110-bambu-residencial-puerto-valalrta-13-150x84.jpg"},"modern-property-child-slider":{"file":"d-110-bambu-residencial-puerto-valalrta-13-680x510.jpg","width":680,"height":510,"mime-type":"image\/jpeg","filesize":42683,"url":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/07\/d-110-bambu-residencial-puerto-valalrta-13-680x510.jpg"},"property-thumb-image":{"file":"d-110-bambu-residencial-puerto-valalrta-13-488x326.jpg","width":488,"height":326,"mime-type":"image\/jpeg","filesize":25076,"url":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/07\/d-110-bambu-residencial-puerto-valalrta-13-488x326.jpg"},"property-detail-video-image":{"file":"d-110-bambu-residencial-puerto-valalrta-13-818x417.jpg","width":818,"height":417,"mime-type":"image\/jpeg","filesize":46486,"url":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/07\/d-110-bambu-residencial-puerto-valalrta-13-818x417.jpg"},"agent-image":{"file":"d-110-bambu-residencial-puerto-valalrta-13-210x210.jpg","width":210,"height":210,"mime-type":"image\/jpeg","filesize":9278,"url":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/07\/d-110-bambu-residencial-puerto-valalrta-13-210x210.jpg"},"partners-logo":{"file":"d-110-bambu-residencial-puerto-valalrta-13-600x720.jpg","width":600,"height":720,"mime-type":"image\/jpeg","filesize":45336,"url":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/07\/d-110-bambu-residencial-puerto-valalrta-13-600x720.jpg"},"post-featured-image":{"file":"d-110-bambu-residencial-puerto-valalrta-13-1240x720.jpg","width":1240,"height":720,"mime-type":"image\/jpeg","filesize":92430,"url":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/07\/d-110-bambu-residencial-puerto-valalrta-13-1240x720.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]},"ID":"9516","name":"d-110-bambu-residencial-puerto-valalrta-13.jpg","path":"\/home\/casaqpta\/casaopcion.com\/en\/wp-content\/uploads\/2024\/07\/d-110-bambu-residencial-puerto-valalrta-13.jpg","url":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/07\/d-110-bambu-residencial-puerto-valalrta-13-150x150.jpg","full_url":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/07\/d-110-bambu-residencial-puerto-valalrta-13.jpg","title":"d-110-bambu-residencial-puerto-valalrta-13","caption":"","description":"","alt":"","srcset":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/07\/d-110-bambu-residencial-puerto-valalrta-13-150x150.jpg 150w, https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/07\/d-110-bambu-residencial-puerto-valalrta-13-210x210.jpg 210w"},{"width":150,"height":150,"file":"2024\/07\/d-110-bambu-residencial-puerto-valalrta-14.jpg","filesize":844221,"sizes":{"medium":{"file":"d-110-bambu-residencial-puerto-valalrta-14-300x169.jpg","width":300,"height":169,"mime-type":"image\/jpeg","filesize":17150,"url":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/07\/d-110-bambu-residencial-puerto-valalrta-14-300x169.jpg"},"large":{"file":"d-110-bambu-residencial-puerto-valalrta-14-1024x576.jpg","width":1024,"height":576,"mime-type":"image\/jpeg","filesize":140423,"url":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/07\/d-110-bambu-residencial-puerto-valalrta-14-1024x576.jpg"},"thumbnail":{"file":"d-110-bambu-residencial-puerto-valalrta-14-150x150.jpg","width":150,"height":150,"mime-type":"image\/jpeg","filesize":8334,"url":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/07\/d-110-bambu-residencial-puerto-valalrta-14-150x150.jpg"},"medium_large":{"file":"d-110-bambu-residencial-puerto-valalrta-14-768x432.jpg","width":768,"height":432,"mime-type":"image\/jpeg","filesize":88465,"url":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/07\/d-110-bambu-residencial-puerto-valalrta-14-768x432.jpg"},"post-thumbnail":{"file":"d-110-bambu-residencial-puerto-valalrta-14-150x84.jpg","width":150,"height":84,"mime-type":"image\/jpeg","filesize":5368,"url":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/07\/d-110-bambu-residencial-puerto-valalrta-14-150x84.jpg"},"modern-property-child-slider":{"file":"d-110-bambu-residencial-puerto-valalrta-14-680x510.jpg","width":680,"height":510,"mime-type":"image\/jpeg","filesize":90529,"url":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/07\/d-110-bambu-residencial-puerto-valalrta-14-680x510.jpg"},"property-thumb-image":{"file":"d-110-bambu-residencial-puerto-valalrta-14-488x326.jpg","width":488,"height":326,"mime-type":"image\/jpeg","filesize":47373,"url":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/07\/d-110-bambu-residencial-puerto-valalrta-14-488x326.jpg"},"property-detail-video-image":{"file":"d-110-bambu-residencial-puerto-valalrta-14-818x417.jpg","width":818,"height":417,"mime-type":"image\/jpeg","filesize":91999,"url":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/07\/d-110-bambu-residencial-puerto-valalrta-14-818x417.jpg"},"agent-image":{"file":"d-110-bambu-residencial-puerto-valalrta-14-210x210.jpg","width":210,"height":210,"mime-type":"image\/jpeg","filesize":15041,"url":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/07\/d-110-bambu-residencial-puerto-valalrta-14-210x210.jpg"},"partners-logo":{"file":"d-110-bambu-residencial-puerto-valalrta-14-600x720.jpg","width":600,"height":720,"mime-type":"image\/jpeg","filesize":106523,"url":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/07\/d-110-bambu-residencial-puerto-valalrta-14-600x720.jpg"},"post-featured-image":{"file":"d-110-bambu-residencial-puerto-valalrta-14-1240x720.jpg","width":1240,"height":720,"mime-type":"image\/jpeg","filesize":214364,"url":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/07\/d-110-bambu-residencial-puerto-valalrta-14-1240x720.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]},"ID":"9517","name":"d-110-bambu-residencial-puerto-valalrta-14.jpg","path":"\/home\/casaqpta\/casaopcion.com\/en\/wp-content\/uploads\/2024\/07\/d-110-bambu-residencial-puerto-valalrta-14.jpg","url":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/07\/d-110-bambu-residencial-puerto-valalrta-14-150x150.jpg","full_url":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/07\/d-110-bambu-residencial-puerto-valalrta-14.jpg","title":"d-110-bambu-residencial-puerto-valalrta-14","caption":"","description":"","alt":"","srcset":"https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/07\/d-110-bambu-residencial-puerto-valalrta-14-150x150.jpg 150w, https:\/\/casaopcion.com\/en\/wp-content\/uploads\/2024\/07\/d-110-bambu-residencial-puerto-valalrta-14-210x210.jpg 210w"}],"REAL_HOMES_change_gallery_slider_type":"0","REAL_HOMES_gallery_slider_type":"thumb-on-right","inspiry_floor_plans":[],"inspiry_video_group":[],"REAL_HOMES_360_virtual_tour":"","REAL_HOMES_tour_video_url":"","REAL_HOMES_tour_video_image":[],"REAL_HOMES_agent_display_option":"none","REAL_HOMES_agents":[],"REAL_HOMES_energy_class":"none","REAL_HOMES_energy_performance":"","REAL_HOMES_epc_current_rating":"","REAL_HOMES_epc_potential_rating":"","REAL_HOMES_sticky":"0","inspiry_property_label":"","inspiry_property_label_color":"","inspiry_property_tax":"0","inspiry_additional_fee":"0","REAL_HOMES_attachments":[],"inspiry_property_owner_name":"","inspiry_property_owner_contact":"","inspiry_property_owner_address":"","REAL_HOMES_property_private_note":"","inspiry_message_to_reviewer":"","REAL_HOMES_add_in_slider":"no","REAL_HOMES_slider_image":[],"REAL_HOMES_page_banner_image":[],"REAL_HOMES_hide_property_advance_search":"0","REAL_HOMES_custom_header_display":"default","REAL_HOMES_custom_header_position":"relative","REAL_HOMES_hide_advance_search":"0","REAL_HOMES_custom_search_form":"default","REAL_HOMES_search_form_margin_top":"","REAL_HOMES_search_form_margin_bottom":"","REAL_HOMES_custom_footer_display":"default"},"_links":{"self":[{"href":"https:\/\/casaopcion.com\/en\/wp-json\/wp\/v2\/properties\/9509","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/casaopcion.com\/en\/wp-json\/wp\/v2\/properties"}],"about":[{"href":"https:\/\/casaopcion.com\/en\/wp-json\/wp\/v2\/types\/property"}],"author":[{"embeddable":true,"href":"https:\/\/casaopcion.com\/en\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/casaopcion.com\/en\/wp-json\/wp\/v2\/comments?post=9509"}],"version-history":[{"count":2,"href":"https:\/\/casaopcion.com\/en\/wp-json\/wp\/v2\/properties\/9509\/revisions"}],"predecessor-version":[{"id":9562,"href":"https:\/\/casaopcion.com\/en\/wp-json\/wp\/v2\/properties\/9509\/revisions\/9562"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/casaopcion.com\/en\/wp-json\/wp\/v2\/media\/9517"}],"wp:attachment":[{"href":"https:\/\/casaopcion.com\/en\/wp-json\/wp\/v2\/media?parent=9509"}],"wp:term":[{"taxonomy":"property-feature","embeddable":true,"href":"https:\/\/casaopcion.com\/en\/wp-json\/wp\/v2\/property-features?post=9509"},{"taxonomy":"property-type","embeddable":true,"href":"https:\/\/casaopcion.com\/en\/wp-json\/wp\/v2\/property-types?post=9509"},{"taxonomy":"property-city","embeddable":true,"href":"https:\/\/casaopcion.com\/en\/wp-json\/wp\/v2\/property-cities?post=9509"},{"taxonomy":"property-status","embeddable":true,"href":"https:\/\/casaopcion.com\/en\/wp-json\/wp\/v2\/property-statuses?post=9509"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}